{"id":40468,"date":"2015-02-03T14:48:45","date_gmt":"2015-02-03T13:48:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/la-coccarda-rossa-1861-grafic-novel-sul-brigantaggio\/"},"modified":"2023-01-17T12:31:54","modified_gmt":"2023-01-17T11:31:54","slug":"18014-la-coccarda-rossa-1861-grafic-novel-sul-brigantaggio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/18014-la-coccarda-rossa-1861-grafic-novel-sul-brigantaggio\/","title":{"rendered":"La Coccarda Rossa 1861, fumetto sul brigantaggio"},"content":{"rendered":"<p>Racconti basati su fatti realmente accaduti.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Una graphic novel nata da un soggetto di Mauro Mercuri che racconta di come i soldati borbonici, insieme ai contadini meridionali, dopo l&#8217;Unit\u00e0 si organizzarono in bande brigantesche per combattere l&#8217;occupazione piemontese. Un volume prodotto con l&#8217;intenzione di veicolare una parte di storia ancora poco conosciuta. La letteratura disegnata, come Umberto Eco ha definito il mondo del fumetto, \u00e8 una forma di comunicazione, diretta, potente e sincera. E<\/p>\n<p>La Coccarda Rossa 1981, edita da Segni d&#8217;Autore parla della Parigi del 1888, dove Rocco,<strong> un giovane emigrato meridionale, incontra in un caff\u00e8 degli Champs Elisee, un anziano signore che crede di conoscere.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Si avvicina, lo guarda negli occhi e immediatamente lo sguardo di quell&#8217;uomo, lo fa&#8217; tornare con la mente a quando da ragazzino accompagnava suo zio a consegnare la verdura al palazzo reale di Napol<strong>i. L\u00ec nel cortile, in una di quelle occasioni, vide Francesco II da vicino.<\/strong> Il Re mentre saliva in carrozza, salut\u00f2 quel giovane laborioso strizzando l&#8217;occhiolino, Rocco emozionato, non dimentic\u00f2 mai quel gesto e quello sguardo, lo stesso sguardo che aveva adesso davanti.<\/p>\n<p>&nbsp;<\/p>\n<p>Inizia cos\u00ec &#8216;La Coccarda Rossa&#8221;, un fumetto che<strong> racconta tramite i ricordi dell&#8217;ultimo Re delle Due Sicilie, le gesta di Nicola Cardone, un ex soldato borbonico, che ancora fedele al suo Re, organizza una banda per reagire all&#8217;occupazione del Meridione.<\/strong> Portavano dei simboli distintivi, tra i quali anelli di zinco e coccarde rosse, con lo scopo di difendersi dalle stragi che i bersaglieri, piemontesi prima e unitari dopo, compivano coperti da una censura che \u00e8 durata decenni. Una cinquantina i testi consultati, che vanno da De Sivo ai pi\u00f9 recenti, oltre a centinaia di documenti visionati presso i vari archivi.<\/p>\n<p>&nbsp;<\/p>\n<p>Un lavoro di ricerca durato quasi un anno, per consentire la realizzazione di un soggetto che riportasse nei minimi dettagli vicende realmente accadute. Infatti ogni pagina riporta avvenimenti riscontrabili nella bibliografia e nei documenti citati nell&#8217;ultima pagina, <strong>come ad esempio gli espedienti che usavano le bande per conoscere gli spostamenti delle truppe, o i travestimenti dei militari per i pedinamenti dei sospetti.<\/strong> Oltre all&#8217;attendibilit\u00e0 dei contenuti, un grande merito va al disegnatore Carlo Rispoli, che ha saputo trasformarli in bellisime immagini.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Racconti basati su fatti realmente accaduti.<\/p>\n","protected":false},"author":22,"featured_media":40469,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,25],"tags":[],"class_list":["post-40468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-libri"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/40468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=40468"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/40468\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/40469"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=40468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=40468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=40468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}