{"id":4047,"date":"2012-09-22T11:07:16","date_gmt":"2012-09-22T09:07:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=4047"},"modified":"2023-01-17T13:37:13","modified_gmt":"2023-01-17T12:37:13","slug":"1174-udc-denise-plastina-nuova-responsabile-del-movimento-giovanile","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/1174-udc-denise-plastina-nuova-responsabile-del-movimento-giovanile\/","title":{"rendered":"Udc: Denise Plastina guida il movimento giovanile"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA <\/strong>&#8211; L&#8217;Italia di Casini riparte dai volti nuovi. <strong>Denise Plastina \u00e8 la nuova responsabile del movimento giovanile dell\u2019Udc per la Citt\u00e0 di Cosenza<\/strong>.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Ad ufficializzare la nomina \u00e8 il commissario dell\u2019Area Urbana Cosentina dei Giovani Udc, Enrico Morcavallo. \u00abSi tratta di una scelta \u2013 afferma Morcavallo \u2013 volta a premiare l\u2019impegno profuso all\u2019interno del gruppo giovanile dello scudo crociato in questi anni dalla pi\u00f9 giovane donna candidata alle scorse competizioni comunali\u00bb.<\/p>\n<p style=\"text-align: justify;\">Anche il commissario provinciale Annamaria Algieri si congratula con la neo-responsabile: \u00abSono certa che l&#8217;impegno dell\u2019amica Denise sar\u00e0 determinante per il percorso di crescita che ha contraddistinto il gruppo giovanile cittadino dell\u2019Udc e per l&#8217;opera di rinnovamento dell\u2019attuale classe politica e dirigente locale\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; L&#8217;Italia di Casini riparte dai volti nuovi. Denise Plastina \u00e8 la nuova responsabile del movimento giovanile dell\u2019Udc per la Citt\u00e0 di Cosenza.<\/p>\n","protected":false},"author":22,"featured_media":2015,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42,5],"tags":[],"class_list":["post-4047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=4047"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4047\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/2015"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=4047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=4047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=4047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}