{"id":40500,"date":"2015-02-04T12:06:53","date_gmt":"2015-02-04T11:06:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/archeologia-2\/"},"modified":"2023-01-17T12:31:55","modified_gmt":"2023-01-17T11:31:55","slug":"18030-archeologia-2","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/18030-archeologia-2\/","title":{"rendered":"Maxioperazione contro il contrabbando di reperti archeologici, perquisizioni anche a Cosenza"},"content":{"rendered":"<p>ROMA &#8211;&nbsp;L&#8217;inchiesta \u00e8 partita dal furto di una porzione di affresco dalla Casa di Nettuno a Pompei.&nbsp;<\/p>\n<p>  <!--more-->  <\/p>\n<p>I carabinieri del comando tutela patrimonio culturale con la collaborazione dei reparti territoriali e mobili coordinati dalla Dda di Napoli hanno eseguito 147 perquisizioni sul territorio nazionale in una vasta indagine senza precedenti contro il traffico illecito di beni culturali. Si tratta di reperti provenienti dalle maggiori aree archeologiche italiane tra cui anche Pompei. 450 i Carabinieri impegnati nella maxi operazione scattata all&#8217;alba in tutta Italia contro il traffico illecito di beni culturali, in particolare &#8211; si \u00e8 saputo a Napoli da fonti investigative &#8211; reperti provenienti da siti archeologici di Campania, Puglia e Sicilia. Anfore e vasi a figure rosse, frammenti architettonici, monete italiche. Sono oltre duemila i beni archeologici sequestrati dai carabinieri dei beni culturali nella maxi operazione in corso da questa mattina in tutta Italia, con 142 decreti di perquisizione emessi dalla Direzione Distrettuale di Napoli ed eseguiti in decine di citt\u00e0 e piccoli centri, da Caltanissetta a Pordenone. <strong>Intitolata &#8220;Artemide&#8221;, l&#8217;indagine punta, spiegano gli investigatori, alla disarticolazione &#8220;di un gruppo strutturato, operante nell&#8217;intera Italia meridionale, in particolare tra Campania e Puglia, dedito agli scavi clandestini, alla ricettazione e all&#8217;illecita commercializzazione di beni culturali&#8221;.<\/strong> Le perquisizioni eseguire all&#8217;alba di oggi nelle provincie di Agrigento, Arezzo, Avellino, Bari, Benevento, Bologna, Brescia, Caltanisetta, Caserta, Catania, Cosenza, Enna, Foggia, Latina, Milano, Napoli, Pordenone, Roma, Salerno, Taranto, Teramo e Viterbo sono state portate a termine dai militari del Comando Carabinieri Tutela Patrimonio Culturale, con l&#8217;ausilio dell&#8217;Arma Territoriale e Mobile e con il supporto dell&#8217;Elinucleo di Pontecagnano. Si tratta, sottolineano dal Comando, di &#8220;un&#8217;operazione senza precedenti per numero di obiettivi e forze impiegate&#8221;. Le operazioni, ancora in corso, avevano gi\u00e0 consentito, nelle fasi preliminari dell&#8217;inchiesta, il recupero di 874 reperti archeologici e l&#8217;arresto di tre indagati in collaborazione col Gruppo Patrimonio Historico della Guardia Civile.<strong> Tra i beni sequestrati anche metal detector e utensili per la ricerca e lo scavo clandestino.&nbsp;<\/strong><span style=\"font-size: 12px;\">Nell&#8217;operazione non vi sono stati finora arresti.&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211;&nbsp;L&#8217;inchiesta \u00e8 partita dal furto di una porzione di affresco dalla Casa di Nettuno a Pompei.&nbsp;<\/p>\n","protected":false},"author":22,"featured_media":40501,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-40500","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/40500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=40500"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/40500\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/40501"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=40500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=40500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=40500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}