{"id":40599,"date":"2015-02-06T13:09:36","date_gmt":"2015-02-06T12:09:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/scriviamo-la-storia-degli-ultra\/"},"modified":"2023-01-17T12:32:02","modified_gmt":"2023-01-17T11:32:02","slug":"18082-scriviamo-la-storia-degli-ultra","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/18082-scriviamo-la-storia-degli-ultra\/","title":{"rendered":"Gli Ultr\u00e0 cosentini preparano un volume per raccontare la loro storia"},"content":{"rendered":"<p>COSENZA &#8211; Gli Ultr\u00e0 di Cosenza raccolgono testimonianze e racconti per ricostruire la loro storia, dalla fondazione fino ai giorni nostri.<\/p>\n<p>  <!--more-->  <\/p>\n<p>&#8221;Da alcuni anni ci chiediamo, e ci propongono, &#8211; affermano gli Ultr\u00e0 cosentini &#8211; di scrivere la storia degli ultr\u00e0 di Cosenza, la nostra storia. \u00c8 un\u2019impresa difficilissima, perch\u00e9 rischiamo di dimenticare qualcuno e qualcosa&#8221;. Per dare vita al progetto, hanno ideato una serie di incontri, coinvolgendo i cittadini di Cosenza e di tutto il resto della provincia. <strong>Durante ogni incontro verranno proiettate foto degli Ultr\u00e0 dal 1978, anno di fondazione, fino ad oggi, e ogni partecipante sar\u00e0 chiamato ad intervenire raccontando i propri ricordi e la propria storia<\/strong>. Il fine \u00e8 quello di unire tutte le testimonianze in una raccolta, organizzata in uno o pi\u00f9 volumi. Gli incontri si terranno presso la casa occupata ex canossiane a viale della Repubblica (inizio della salita dell&#8217;acquedotto), e saranno trasmessi in diretta streaming per permettere anche ai tifosi distanti di partecipare. Il primo appuntamento si svolger\u00e0 domani alle 18:00, e al termine di ogni assemblea verr\u00e0 organizzata una cena sociale. <strong>Il ricavato sosterr\u00e0 l&#8217;autorecupero della Casa Occupata, attualmente abitata da cosentini e migranti<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Gli Ultr\u00e0 di Cosenza raccolgono testimonianze e racconti per ricostruire la loro storia, dalla fondazione fino ai giorni nostri.<\/p>\n","protected":false},"author":22,"featured_media":40600,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-40599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/40599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=40599"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/40599\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/40600"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=40599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=40599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=40599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}