{"id":4060,"date":"2012-09-22T14:43:19","date_gmt":"2012-09-22T12:43:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=4060"},"modified":"2023-01-17T13:37:14","modified_gmt":"2023-01-17T12:37:14","slug":"1187-crotone-bari-calil-spreca-il-bonus-dagli-undici-metri","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/1187-crotone-bari-calil-spreca-il-bonus-dagli-undici-metri\/","title":{"rendered":"Crotone-Bari, Calil spreca il bonus dagli undici metri"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>CROTONE &#8211;<\/strong> Due punti persi dagli undici metri. Il Crotone si mangia letteralmente le mani per non aver saputo sfruttare quell&#8217;occasione che, al 48&#8242; del secondo tempo, l&#8217;arbitro aveva concesso ai padroni di casa. Il bonus da tre punti \u00e8 stato sprecato. A procurarsi il penalty e da incaricarsi di batterlo \u00e8 stato Calil. Il rigore calciato dallo stesso attaccante pitagorico ha esaltato i riflessi del pipelt barese, Lamanna che ha parato il rigore, facendo esultare la sua squadra poer il pericolo scampato, proprio sui titoli di coda. Per come i due allenatori avevano disegnato le squadre in campo, gli sportivi assipetati sugli spalti dello Scida, erano convinti di vedere una partita ricca di emozioni. Il 4-2-3-1 di Drago contro il 4-3-3 di Torrente, Crotone-Bari \u00e8 anche questo e non \u00e8 un caso che la partita andata in campo allo Scida si sia rivelata gradevole. L&#8217;occasione pi\u00f9 ghiotta nel primo tempo \u00e8 per i paddroni di casa che, intorno alla mezz&#8217;ora, colpiscono la traversa con un tiro da fuori di Ciano, il tap in di Eramo si spegne alto sopra la traversa. Qualche minuto dopo proprio il centrocampista pitagorico ci riprova sfruttando un cross dalla sinistra, stavolta la sua conclusione \u00e8 nello specchio, ma \u00e8 Lamanna a rendersi protagonista di una grande parata. Il conto dei legni, in una gara senza esclusione di colpi in cui le due squadre vanno a mille, lo pareggia il talentuoso Bellomo, che al 50&#8242; trova il montante con una conclusione da quasi trenta metri. Clamorosa l&#8217;occasione fallita da Pettinari a met\u00e0 della ripresa che, con la porta vuota, non trova l&#8217;impatto con il pallone.. Al 93&#8242;, come dicevamo, la grande opportunit\u00e0 per i padroni di casa, Defedendi atterra Calil in area, per l&#8217;arbitro Pairetto \u00e8 rigore. &nbsp;Tocca al brasiliano calciare, ma Lamanna respinge la conclusione, un attimo prima del triplice fischio finale.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE &#8211; Due punti persi dagli undici metri. Il Crotone si mangia letteralmente le mani per non aver saputo sfruttare quell&#8217;occasione che, al 48&#8242; del secondo tempo, l&#8217;arbitro aveva concesso ai padroni di casa. Il bonus da tre punti \u00e8 stato sprecato. A procurarsi il penalty e da incaricarsi di batterlo \u00e8 stato Calil. Il [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":2041,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,5,20],"tags":[],"class_list":["post-4060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-old","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=4060"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/2041"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=4060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=4060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=4060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}