{"id":40606,"date":"2015-02-06T14:48:08","date_gmt":"2015-02-06T13:48:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/castrovillari-convegno-giuridico\/"},"modified":"2023-01-17T12:32:02","modified_gmt":"2023-01-17T11:32:02","slug":"18086-castrovillari-convegno-giuridico","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/18086-castrovillari-convegno-giuridico\/","title":{"rendered":"Castrovillari, convegno giuridico &#8211; antropologico tra costume e realt\u00e0, a partire dal caso della Baronessa di Carini"},"content":{"rendered":"<p>CASTROVILLARI (CS) &#8211; Tra giurisprudenza, realt\u00e0 e antropologia in una full immersion che richiama fatti realmente avvenuti.<\/p>\n<p>  <!--more-->  <\/p>\n<p>A partire da questi presupposti, domani nella sala 14 del Protoconvento francescano di Castrovillari, dalle 17:00, si affronter\u00e0 il tema \u201cLe basi romanistiche dell\u2019adulterio nella disciplina moderna e contemporanea dell\u2019Istituto. Il caso di Carini tra il Diritto Comune e la Tradizione popolare dei cantastorie\u201d. <strong>Questa intricata storica vicenda siciliana, con molti punti interrogativi, che interess\u00f2, tanti anni fa, l\u2019uccisione di una donna, la baronessa Laura Lanza di Trabia, ed il suo amante, Ludovico Vernagallo<\/strong>, cantata in pi\u00f9 versioni dalla tradizione popolare e oggetto, tra l\u2019altro, di diverse interpretazioni espressive, a partire pure da un poemetto che spiegava, unendo la verit\u00e0 al mistero ed alla leggenda, la passione amorosa sfociata nell\u2019adulterio e nella morte. Il tema ritorna, prepotentemente, proposto in un convegno giuridico per divenire occasione di approfondimento degli Istituti del diritto. <strong>Il convegno<\/strong>, organizzato dalla Camera Civile e dal Consiglio dell\u2019Ordine degli Avvocati di Castrovillari con il patrocinio del Comune e in collaborazione con l\u2019associazione culturale Mystica Calabria, si svilupper\u00e0 con il contributo di studiosi, <strong>antropologi oltre che di uomini di legge<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Dopo i saluti del Commissario straordinario del Comune, Massimo Mariani, di Roberto Laghi, Presidente dell\u2019Ordine degli Avvocati di Castrovillari, sono previste, moderate da Ines Ferrante, Presidente di Mystica Calabria, le <strong>relazioni di<\/strong>: Giovanni Brandi Cordasco Salmena di San Quirico, docente di Diritto Romano Ellenistico presso la facolt\u00e0 di Giurisprudenza di Urbino che approfondir\u00e0 \u201cI principi della Lex Iulia de adulteriis nella disciplina moderna e contemporanea dell\u2019istituto\u201d; di Leonardo Alario, docente di Storia delle tradizioni popolari all\u2019Unical ed all\u2019Ateneo di Bari, che riguarder\u00e0 \u201cChianci Palermu, chianci Siracusa a Carini c&#8217;\u00e8 lu luttu in ogni casa. L\u2019amaro caso di la barunissa tra critica, storia e tradizione popolare\u201d; di Antonella Gialdino, Presidente della Camera Civile degli Avvocati di Castrovillari che affronter\u00e0 il tema de \u201cLa famiglia nell\u2019ordinamento giuridico italiano\u201d; di Giovanni Zagarese, Presidente della Camera Penale di Rossano che interverr\u00e0 su \u201cL\u2019 omicidio per causa di onore\u201d dell\u2019art. 587 cp. fino all\u2019abrogazione dell&#8217;art. 1 L. 5 agosto 1981 n. 442\u201d; di Vincenzo Di Pede, magistrato e Presidente della Sezione Civile del Tribunale di Castrovillari che tratter\u00e0 \u201cIl rilievo attuale dell\u2019adulterio nel giudizio di separazione personale dei coniugi. Vecchie e nuove prospettive\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASTROVILLARI (CS) &#8211; Tra giurisprudenza, realt\u00e0 e antropologia in una full immersion che richiama fatti realmente avvenuti.<\/p>\n","protected":false},"author":22,"featured_media":40607,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-40606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/40606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=40606"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/40606\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/40607"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=40606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=40606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=40606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}