{"id":40876,"date":"2015-02-15T11:40:22","date_gmt":"2015-02-15T10:40:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/catanzaro-cosenza-live-0-0\/"},"modified":"2023-01-17T12:32:18","modified_gmt":"2023-01-17T11:32:18","slug":"18226-catanzaro-cosenza-live-0-0","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/18226-catanzaro-cosenza-live-0-0\/","title":{"rendered":"Il Cosenza sbaglia troppo e un cinico Catanzaro vince il derby di Calabria con un solo tiro in porta"},"content":{"rendered":"<p>CATANZARO &#8211; &nbsp;Va ai giallorossi il derby di Calabria. Catanzaro bravo e cinico a sfruttare l&#8217;unico tiro in porta della partita, mentre il Cosenza deve fare il mea culpa per le troppe occasioni da rete sprecate soprattutto nella prima frazione di gara. Match winner del match Bernardo al 46&#8242; del secondo tempo. Cosenza in 10 negli ultimi 10 minuti per l&#8217;espulsione di Cori per proteste.<\/p>\n<p>  <!--more-->  <\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #0000ff;\"><strong>Primo Tempo<\/strong><\/span><\/p>\n<p>&nbsp;Le due squadre scendono in campo. Cosenza in divisa bianca, Catanzaro con la classica tenuta giallorossa<\/p>\n<p>1&#8242; &#8211; &nbsp;Via al match: il Cosenza attaccher\u00e0 da sinistra a destra<\/p>\n<p>5&#8242; &nbsp;&#8211;<strong>&nbsp; Bolide di Arrigoni dai 25 metri e palla che colpisce in pieno la traversa con Bindi battuto<\/strong><\/p>\n<p>11&#8242; &#8211; Blondett rimane a terra dopo uno scontro di gioco, ma rientra anche se dolorante<\/p>\n<p>12&#8242;- <strong>Occasione da rete per i giallorossi: grande girata di sinistro di Mancuso al limite dell&#8217;area e palla che colpisce il palo alla sinistra di Ravaglia<\/strong><\/p>\n<p>13&#8242; &#8211; Punizione per il Cosenza al limite dell&#8217;area. Batte Arrigoni con un destro a giro sul palo difeso da Bindi, che non si lascia sorprendere e manda la palla in angolo<\/p>\n<p>20&#8242; &#8211; Partita equilibrata con il Cosenza che non si tira indietro e cerca di affrontare i giallorossi a viso aperto<\/p>\n<\/p>\n<p>&nbsp;<\/p>\n<p>25&#8242; &#8211; Il Catanzaro spinge con pi\u00f9 convinzione, ma il Cosenza si difende con ordine non lasciando spazi alla manovra dei giallorossi;<\/p>\n<p>26 &#8216; &#8211; Ci prova Statella dopo una veloce ripartenza del Cosenza ma il tro \u00e8p debole e Bindi blocca a terra senza problemi<\/p>\n<p>29&#8242; &#8211; Cambio per il Cosenza: Blondett non ce la fa e lascia il campo a Zanini<\/p>\n<p>33 &#8216; &#8211; Si fa vivo il Catanzaro con un tiro dal limite che chiama Ravaglia alla deviazione<\/p>\n<p><strong>34 &#8216; &#8211; Incredibile azione da rete sbagliata da Statella che liberato da solo davanti il portiere angola troppo il tiro che finisce fuori<\/strong><\/p>\n<p>37&#8242; &#8211; Ancora pericolosissimi i rossoblu con un bolide dello stesso Statella dai 28 metri, che fa la barba al palo.<\/p>\n<p>38&#8242; &#8211; Partita non proprio bellissima dal punto di vista del gioco ma le due squadre non si risparmiano lottando su tutti i palloni<\/p>\n<p>44&#8242; &#8211; Catanzaro pericoloso con un colpo di testa di Mancuso da ottima posizione su cross proveniente dalla destra ma la palla sorvola la traversa<\/p>\n<p>48&#8242; &#8211; Dopo 3 minuti di recupero finisce un primo tempo poco spettacolare ma molto combattuto.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #0000ff;\"><strong>Secondo tempo<\/strong><\/span><\/p>\n<p><strong>46&#8242; &#8211; Pronti via e il Catanzaro passa in vantaggio: cross di Squillace dalla sinistra, Bernardo di testa anticipa Magli e insacca alla sinistra di Ravaglia<\/strong><\/p>\n<p>47&#8242; &#8211; &nbsp;Buttissimo fallo da dietro di Zappacosta su Caccetta che rimedia il primo giallo della partita<\/p>\n<p>53&#8242; &#8211; Il Cosenza prova a reagire subito allo svantaggio riversandosi nella met\u00e0 campo giallorossa ma le azioni dei rossoblu sono confusionarie e la difesa di casa riesce a difendersi senza affanni<\/p>\n<p>58 &#8216; &#8211; Secondo cambio nel Cosenza dopo la sostituzione obbligata di Blondett nella prima frazione: fuori De Angelis dentro Calderini7<\/p>\n<p>64&#8242; &#8211; Catanzaro di rimessa che si rende pericoloso con un tiro di Razzitti da dentro l&#8217;area di rigore sventato da Ravaglia<\/p>\n<p>66&#8242; &nbsp;&#8211; Ultimo cambio per il Cosenza: dentro l&#8217;ex Tortolano al posto di Caccetta auto, bisogna dirlo, di un&#8217;ottima prova<\/p>\n<p>68&#8242; &#8211; Statella si invola sulla destra e dal fondo mette dentro una palla per Cori che svetta di testa ma riesce solo a sfiorare il pallone che si perde sul fondo<\/p>\n<p>71&#8242; &#8211; Ammonito Statella per simulazione&nbsp;<\/p>\n<p>75&#8242; &#8211; Primo cambio nel Catanzaro di Sanderra: fuori Giandonato e dentro Ilari<\/p>\n<p>76&#8242; Gara diventata ancora pi\u00f9 brutta, con molti errori da una parte e dell&#8217;altra<\/p>\n<p>77&#8242; ammonito Rigione per una gomitata su Cori. Sulla susseguente punizione Arrigoni spara alto sulla traversa<\/p>\n<p><strong>78&#8242; &#8211; Cosenza vicinissimo al pareggio: Calderini semina il panico sulla corsia di sinistra e mette un pallone al centro per Tortolano che appoggia per l&#8217;accorrente Arrigoni che tira dal limite di prima intenzione, ma Bindi si supera e respinge il tiro<\/strong><\/p>\n<p>82&#8242; &#8211; Massimo sforzo per il Cosenza che ha chiuso il Catanzaro nella propria met\u00e0 campo<\/p>\n<p>84&#8242; &nbsp;&#8211; Zappacosta perde palla, Torolano la ruba e da 25 metri prova subito la conclusione, ma il tiro \u00e8 centrale e Bindi non ha difficolt\u00e0 a bloccare a terra<\/p>\n<p><strong>85&#8242; &#8211; Cosenza in 10 uomini. Cori esagera nelle proteste e il signor Fiore di Barletta prima lo ammonisce e poi manda l&#8217;attaccante del Cosenza negli spogliatoi<\/strong><\/p>\n<p>87&#8242; &#8211; Cambio nel Catanzaro. Esce l&#8217;attaccante Razzitti per far posto a Mounard.<\/p>\n<p>90&#8242; &#8211; Saranno 5 i minuti di recupero&nbsp;<\/p>\n<p>95&#8242; &#8211; L&#8217;ultimo tiro della partita \u00e8 di Corsi che ci prova da lontano ma Bindi \u00e8 attento<\/p>\n<p>FINALE &#8211; Il Catanzaro ha battuto il Cosenza per 1 a 0<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Catanzaro &#8211; Cosenza<\/strong>: 1 &#8211; 0<\/p>\n<p><strong>Marcatori<\/strong>: 46&#8242; Bernardo<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Catanzaro<\/strong>: Bindi, Daffara, Squillace, Giandonato (75&#8242; Ilari), Rigione, Orchi, Giamp\u00e0, Mancuso, Razzitti, Zappacosta, Bernardo<\/p>\n<p><strong>Panchina<\/strong>: Migani, D&#8217;Orsi, Badara, Russotto, Mounard, Caputa, Ilari<\/p>\n<p><strong>Allenatore<\/strong>: Paolo Indiani<\/p>\n<p>&nbsp;(66<\/p>\n<p><strong>Cosenza Calcio<\/strong>: Ravaglia, Ciancio, Blondett (29&#8242; Zanini), Arrigoni, Tedeschi, Magli, Corsi, Caccetta (66&#8242; Tortolano), Cori, De Angelis (58&#8242; Calderini), Statella<\/p>\n<p><strong>Panchina<\/strong>: Saracco, Zanini, Criaco, Fornito, Tortolano, Calderini, Cesca<\/p>\n<p><strong>Allenatore<\/strong>: Giorgio Roselli<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Arbitro<\/strong>: Fiore di Barletta<\/p>\n<p><strong> Ammoniti<\/strong>: Zappacosta (CZ), Statella (CS), Bernardo (CZ), Rigione (CZ)<\/p>\n<p><strong>Espulsi<\/strong>: Cori(CS)<\/p>\n<p><strong>Angoli<\/strong>: 6 &#8211; 4<\/p>\n<p><strong> Note<\/strong>: Giornata fresca e nuvolosa, con terreno in ottime condizioni, Presenti 4.871 spettatori (3.111 paganti + 1.760 abbonati) per un incasso di 20.841 euro. Presenti anche 254 supporter rossoblu sistemati nel loro settore. Prima del fischio di inizio le due squadre hanno osservato un minuto di silenzio nel ricordo di Luigi Torani, ex calciatore del Catanzaro scomparso<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-38231\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/aaaCatanzaro_Cosenza_02.jpg\" alt=\"aaaCatanzaro Cosenza 02\" width=\"640\" height=\"427\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-38232\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/aaaCatanzaro_Cosenza_05.jpg\" alt=\"aaaCatanzaro Cosenza 05\" width=\"640\" height=\"427\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-38233\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/aaaCatanzaro_Cosenza_06.jpg\" alt=\"aaaCatanzaro Cosenza 06\" width=\"640\" height=\"427\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-38234\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/aaaCatanzaro_Cosenza_03.jpg\" alt=\"aaaCatanzaro Cosenza 03\" width=\"640\" height=\"427\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-38235\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/02\/aaaCatanzaro_Cosenza_08.jpg\" alt=\"aaaCatanzaro Cosenza 08\" width=\"640\" height=\"427\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; &nbsp;Va ai giallorossi il derby di Calabria. Catanzaro bravo e cinico a sfruttare l&#8217;unico tiro in porta della partita, mentre il Cosenza deve fare il mea culpa per le troppe occasioni da rete sprecate soprattutto nella prima frazione di gara. Match winner del match Bernardo al 46&#8242; del secondo tempo. Cosenza in 10 [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":40877,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,20],"tags":[],"class_list":["post-40876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/40876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=40876"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/40876\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/40877"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=40876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=40876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=40876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}