{"id":4091,"date":"2012-09-24T06:19:30","date_gmt":"2012-09-24T04:19:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=4091"},"modified":"2023-01-17T13:37:18","modified_gmt":"2023-01-17T12:37:18","slug":"1220-rossano-mercoledi-si-festeggia-san-nilo-tra-devizione-e-attrazione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/1220-rossano-mercoledi-si-festeggia-san-nilo-tra-devizione-e-attrazione\/","title":{"rendered":"Rossano, mercoled\u00ec si festeggia San Nilo tra devizione e attrazione"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>ROSSANO &#8211; <\/strong>L&#8217;evento pi\u00f9 atteso. Sono in via di completamento gli ultimi ritocchi organizzativi per la festa di San Nilo Abate, santo patrono del comune jonico, in programma mercoled\u00ec. Il calendario degli eventi prevede che alle 10:30, tutti in chiesa per la celebrazione della Santa Messa, all\u2019interno della chiesa di San Nilo. La funzine litugica sar\u00e0 officiata da monsignor Francesco Milito (Vescovo di Oppido Mamertina-Palmi), mentre alle ore 17 ci sar\u00e0 la tradizionale processione del simulacro del Santo per le vie principali del centro storico.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Riccoe variegato anche il programma della serata. Alle 20:30, nella centralissima Piazza Steri, apertura al pubblico della torre dell\u2019orologio e giochi gonfiabili per i bambini. Lungo Corso Garibaldi, invece, saranno allestiti i tradizionali mercatini dell\u2019artigianato artistico ed esposizione d\u2019arte. Per l\u2019occasione, poi, saranno allestiti, tra l\u2019altro, una serie di stand enogastronomici con la degustazione di prodotti e piatti tipici locali. Alle 21, in Piazza della Vittoria (Monumento dei Caduti), concerto live con il gruppo musicale: \u201cConsheart Island.\u201d Alle 21:30, nell\u2019area di fronte alla Chiesa di San Nilo, si dar\u00e0 vita alla rievocazione storico-teatrale itinerante della vita di San Nilo a cura dell\u2019Associazione \u201cLoco-Motiva\u201d e dall\u2019Associazione culturale \u201cLa Citt\u00e0 del Sole\u201d di Tommaso Campanella. La rievocazione storico-teatrale itinerante, dunque, \u00e8 un viaggio fisico ed emozionale attraverso la storia di Rossano e, in particolare, delle vicende della vita di San Nilo. Alle 22, in Piazza Steri, concerto live con il gruppo musicale: \u201cEnsemble Acoustique\u201d e, alle 23:30, spettacolo pirotecnico sul colle Santa Croce. Una festa che, ogni anno, richiama tanti devoti e molta gente nell\u2019incantevole centro storico bizantino per partecipare, ovviamente, sia alla tradizionale processione che ai festeggiamenti civili programmati dall\u2019Amministrazione comunale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROSSANO &#8211; L&#8217;evento pi\u00f9 atteso. Sono in via di completamento gli ultimi ritocchi organizzativi per la festa di San Nilo Abate, santo patrono del comune jonico, in programma mercoled\u00ec. Il calendario degli eventi prevede che alle 10:30, tutti in chiesa per la celebrazione della Santa Messa, all\u2019interno della chiesa di San Nilo. La funzine litugica [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":2103,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18,5],"tags":[],"class_list":["post-4091","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=4091"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4091\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/2103"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=4091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=4091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=4091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}