{"id":41338,"date":"2015-03-01T19:36:11","date_gmt":"2015-03-01T18:36:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/guarda-le-immagini-paganese-cosenza-la-fotogallery-della-partita\/"},"modified":"2023-01-17T12:32:44","modified_gmt":"2023-01-17T11:32:44","slug":"18464-guarda-le-immagini-paganese-cosenza-la-fotogallery-della-partita","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/18464-guarda-le-immagini-paganese-cosenza-la-fotogallery-della-partita\/","title":{"rendered":"(GUARDA LE IMMAGINI) Paganese &#8211; Cosenza. La fotogallery della partita"},"content":{"rendered":"<p>Guarda subito le foto della partita tra Paganese e Cosenza disputata questa mattina e terminata sul risultato di parit\u00e0<\/p>\n<p>  <!--more-->  <\/p>\n<p>COSENZA &#8211; La redazione di QuiCosenza.it vi regala le foto pi\u00f9 belle dell&#8217;incontro di calcio tra Paganese e Cosenza, valevole per la 27&#8242; giornata del campionato di Lega Pro girone C. L&#8217;incontro si \u00e8 giocato allo Stadio &#8220;Macello Torre&#8221; di Pagani questa mattina ed \u00e8 terminata senza reti.<strong> {imageshow sl=224 sc=3 \/}<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Guarda subito le foto della partita tra Paganese e Cosenza disputata questa mattina e terminata sul risultato di parit\u00e0<\/p>\n","protected":false},"author":23,"featured_media":41339,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,20],"tags":[],"class_list":["post-41338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/41338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=41338"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/41338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/41339"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=41338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=41338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=41338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}