{"id":41829,"date":"2015-03-14T09:17:46","date_gmt":"2015-03-14T08:17:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/maltratta-i-genitori-anziani-ricoverato-in-struttura-psichiatrica\/"},"modified":"2023-01-17T12:33:15","modified_gmt":"2023-01-17T11:33:15","slug":"18721-maltratta-i-genitori-anziani-ricoverato-in-struttura-psichiatrica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/18721-maltratta-i-genitori-anziani-ricoverato-in-struttura-psichiatrica\/","title":{"rendered":"Maltratta i genitori anziani, ricoverato in struttura psichiatrica"},"content":{"rendered":"<p>BIVONGI (RC) &#8211; Ha minacciato e maltrattato i genitori fino a costringerli ad abbandonare la propria abitazione per trasferirsi temporaneamente in una casa di riposo.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Sono queste le ragioni per cui un quarantacinquenne \u00e8 stato ricoverato in una casa di cura e custodia nella struttura psichiatrico &#8211; giudiziaria di Barcellona Pozzo di Gotto (Messina).<strong> Il provvedimento, emesso dal gip del Tribunale di Locri, \u00e8 stato messo in atto a seguito delle indagini dei carabinieri di Stilo, ai quali i genitori dell&#8217;uomo si erano rivolti lo scorso 3 marzo denunciando i maltrattamenti<\/strong>. Nell&#8217;attesa della decisione del gip, i carabinieri hanno sottoposto a sorveglianza l&#8217;uomo che, dopo essersi scagliato contro gli stessi e il personale medico del 118 e del Centro di salute mentale di Gioiosa Jonica accusandoli di avergli sottratto i propri genitori, \u00e8 stato sedato e sottoposto a trattamento sanitario obbligatorio.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BIVONGI (RC) &#8211; Ha minacciato e maltrattato i genitori fino a costringerli ad abbandonare la propria abitazione per trasferirsi temporaneamente in una casa di riposo.<\/p>\n","protected":false},"author":22,"featured_media":41830,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-41829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/41829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=41829"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/41829\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/41830"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=41829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=41829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=41829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}