{"id":41958,"date":"2015-03-19T04:33:32","date_gmt":"2015-03-19T03:33:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/terrorismo-a-tunisi-sindaco-catanzaro-sollievo-per-i-nostri-studenti\/"},"modified":"2023-01-17T12:33:22","modified_gmt":"2023-01-17T11:33:22","slug":"18788-terrorismo-a-tunisi-sindaco-catanzaro-sollievo-per-i-nostri-studenti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/18788-terrorismo-a-tunisi-sindaco-catanzaro-sollievo-per-i-nostri-studenti\/","title":{"rendered":"Nessun pericolo per gli studenti catanzaresi in visita a Tunisi"},"content":{"rendered":"<p>CATANZARO &#8211; Alcuni studenti dell&#8217;Istituto pedagogico di Catanzaro sono in gita turistica a Tunisi.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Lo si \u00e8 appreso dal sindaco di Catanzaro, Sergio Abramo, che ha contattato il preside della scuola, Luigi Macr\u00ec, dal quale ha appreso che i ragazzi non hanno vissuto alcuna situazione di pericolo. Gli studenti, nel momento dell&#8217;attentato, erano in una zona distante da quella presa di mira dai terroristi. I ragazzi ora sono a bordo della nave che li riporter\u00e0 in Italia. &#8220;Ho tirato un sospiro di sollievo quando ho avuto notizie degli studenti dell&#8217;istituto pedagogico di Catanzaro Lido in gita a Tunisi, colpita nelle scorse ore da un drammatico attentato terroristico che ha provocato diverse vittime&#8221;. Lo afferma il sindaco di Catanzaro, Sergio Abramo, dopo aver appreso che gli studenti del capoluogo calabrese in gita a Tunisi non hanno vissuto alcuna situazione di pericolo. Diciassette studenti della provincia di Vibo Valentia sono a bordo di una nave della Msc insieme alla scolaresca dell&#8217;Istituto pedagogico di Catanzaro Lido. Gli studenti di un istituto delle Preserre vibonesi non sono scesi a Tunisi dalla nave perch\u00e8 avevano delle attivit\u00e0 educative in corso. Gli studenti hanno ripreso il viaggio di ritorno, insieme a quelli di Catanzaro, per rientrare in Italia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Alcuni studenti dell&#8217;Istituto pedagogico di Catanzaro sono in gita turistica a Tunisi.<\/p>\n","protected":false},"author":22,"featured_media":41959,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-41958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/41958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=41958"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/41958\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/41959"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=41958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=41958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=41958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}