{"id":42071,"date":"2015-03-21T10:12:40","date_gmt":"2015-03-21T09:12:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/taglio-di-alberi-indiscriminato-miceli-m5s-ora-abbattono-anche-le-palme\/"},"modified":"2023-01-17T12:33:28","modified_gmt":"2023-01-17T11:33:28","slug":"18846-taglio-di-alberi-indiscriminato-miceli-m5s-ora-abbattono-anche-le-palme","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/18846-taglio-di-alberi-indiscriminato-miceli-m5s-ora-abbattono-anche-le-palme\/","title":{"rendered":"Taglio di alberi indiscriminato, a Rende si abbattono anche le palme e le piante in salute"},"content":{"rendered":"<p>RENDE \u2013 Pi\u00f9 tagliano e pi\u00f9 guadagnano.<\/p>\n<p>  <!--more-->  <\/p>\n<p>&#8220;Pare che sia questo &#8211; denuncia il <span style=\"font-size: 12px; line-height: 10.9090909957886px;\">Gruppo consiliare Movimento 5 Stelle Rende &#8211;&nbsp;<\/span>il motivo per cui l\u2019amministrazione abbia affidato gratuitamente il servizio di potatura a ditte esterne, anzich\u00e9 alla Rende Servizi. Infatti \u00e8 da accreditare al fatto che pi\u00f9 legna riescono a tagliare e pi\u00f9 possono ricavarne utile la motivazione della potatura selvaggia che in questi giorni sta interessando il verde rendese. Continua cos\u00ec il taglio indiscriminato di alberi portato avanti dalle ditte incaricate \u201cgratuitamente\u201d dal Comune.&nbsp;<strong>Ieri siamo stati contattati dai residenti del Villaggio Europa che hanno contestato l\u2019abbattimento di alcuni alberi \u201cin perfetta salute\u201d.<\/strong> Giunti sul luogo, ci siamo resi conto con i nostri occhi che le ditte incaricate dal Comune di procedere alla potatura delle piante, o all\u2019abbattimento di quelle malate, \u00e8 andata oltre, tranciando di netto anche alberi che non presentavano assolutamente alcun problema.<\/p>\n<p>&nbsp;<\/p>\n<p>E che anzi, vista la presenza nel parco del villaggio Europa di <strong>un gazebo in legno che d\u2019estate ospita molti anziani, ha tolto loro anche quella frescura che tali piante garantivano.<\/strong>&nbsp;Da qui l\u2019ulteriore lamentela dei residenti che ci hanno inoltre spiegato e fatto vedere che il lavoro ben svolto sugli alberi fronte strada (dove \u00e8 stata eseguita solo la potatura) \u00e8 stato distruttivo su quelle pi\u00f9 nascoste (lato palazzi). Ma c\u2019\u00e8 di pi\u00f9. Perch\u00e9 nel luogo dove sono stati accatastati gli alberi tagliati, o le parti di potatura, abbiamo potuto notare anche delle palme. E non riusciamo a spiegarci come questo sia possibile. Ci chiediamo: erano per caso state contagiate dal punteruolo rosso?&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Perch\u00e9, se cos\u00ec fosse, le ditte che hanno provveduto al taglio indiscriminato avrebbero violato l\u2019ordinanza della Regione Calabria \u2013 Dipartimento n\u00b0 6 Agricoltura, Foreste e forestazione \u2013 Servizio fitosanitario regionale, recepita dall\u2019ordinanza sindacale n\u00b0 180 del 3-12-2014, che regola<strong> il taglio delle palme affette dal punteruolo rosso attraverso una procedura di sicurezza ben determinata (e anche dispendiosa).&nbsp;<\/strong>Come Movimento 5 Stelle siamo costretti ad unirci al coro di no che hanno gi\u00e0 espresso perplessit\u00e0 rispetto a questo taglio indiscriminato di alberi (che ha portato anche a manifestazioni simboliche come la ripiantumazione di alcuni arbust ideata dal consigliere Massimiliano De Rose di Rende cambia Rende) e ora anche di piante di Palme. Auspichiamo un ravvedimento repentino dell\u2019amministrazione Manna a difesa del verde della nostra citt\u00e0, attraverso un piano serio e non indiscriminato. Ci chiediamo se dopo tutte queste polemiche sia stata redatta una perizia tecnica che indichi quali piante devono essere tagliate e quali no. Perch\u00e9, secondo noi, solo con questa perizia si dovrebbe procedere. E se esiste sarebbe anche il caso di renderla pubblica&#8221;.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE \u2013 Pi\u00f9 tagliano e pi\u00f9 guadagnano.<\/p>\n","protected":false},"author":21,"featured_media":42072,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,44],"tags":[],"class_list":["post-42071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/42071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=42071"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/42071\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/42072"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=42071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=42071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=42071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}