{"id":42245,"date":"2015-03-27T07:02:10","date_gmt":"2015-03-27T06:02:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/maltempo-oggi-criticita-rossa-in-calabria\/"},"modified":"2023-01-17T12:33:38","modified_gmt":"2023-01-17T11:33:38","slug":"18937-maltempo-oggi-criticita-rossa-in-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/18937-maltempo-oggi-criticita-rossa-in-calabria\/","title":{"rendered":"(FOTO) Maltempo, allarme rosso oggi in Calabria: torrente esondato a Falerna, traffico deviato tra Amantea e Campora"},"content":{"rendered":"<p>ROMA &#8211; La statale 18, Tirrena Inferiore, \u00e8 stata chiusa a causa di un allagamento.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Allerta della Protezione civile per forti venti e temporali. Criticita&#8217; &#8216;rossa&#8217; prevista in particolare su Calabria e Basilicata. Dopo i primi accenni di primavera proseguono gli effetti della vasta area depressionaria attiva sul mar Mediterraneo Centro-Occidentale, che dall&#8217;inizio della settimana ha determinato condizioni di maltempo, in particolar modo sulle regioni meridionali, e che contribuir\u00e0 ancora ad apportare una moderata instabilit\u00e0 su gran parte del nostro Paese, con fenomeni localmente persistenti e un rinforzo dei venti settentrional<strong>i. Sulla base delle previsioni disponibili, il Dipartimento della Protezione Civile d&#8217;intesa con le Regioni coinvolte ha emesso un nuovo avviso di condizioni meteorologiche avverse a partire da stamane con mareggiate lungo le coste esposte ai venti di maestrale.<\/strong> Sulla base dei fenomeni previsti ed in atto, \u00e8 stata valutato l&#8217;allarme rosso per rischio idrogeologico localizzato sulla Calabria meridionale, mentre &#8216;criticit\u00e0 arancione&#8217; \u00e8 prevista sulle restanti zone della regione.<\/p>\n<p>&nbsp;<\/p>\n<p>Intanto un violento temporale si \u00e8 abbattuto nelle scorse ore nel catanzarese provocando danni e disagi nella zona tirrenica della provincia. A causa della pioggia abbondante \u00e8 esondato il torrente Grima, tra i comuni di Gizzeria e Falerna. Nella zona di Lamezia Terme, Gizzeria e Falerna si sono inoltre verificati allagamenti e danni a diverse strutture. Per far fronte alla situazione sono a lavoro i vigili del fuoco e squadre di intervento dei comuni interessati. L&#8217;Anas ha reso noto che sulla Tirrena Inferiore un tratto \u00e8 provvisoriamente chiuso al traffico tra Amantea e Campora San Giovanni a causa di un allagamento al km 364,8, in localit\u00e0 Gizzeria Lido provocato dall&#8217;esondazione del torrente che avrebbe danneggiato parte della ss 18. Le deviazioni sono segnalate in loco.&nbsp;<strong>Il torrente in piena avrebbe infatti eroso il terreno posizionato sotto l&#8217;asfalto, rimasto quindi sospeso nel vuoto.<\/strong>&nbsp;Gli automobilisti sono da ora invitati a utilizzare l&#8217;autostrada Salerno-Reggio Calabria come unica via di collegamento per la fascia tirrenica.&nbsp;Le previsioni meteo hanno indotto il sindaco di Reggio Calabria, Giuseppe Falcomat\u00e0, a chiudere precauzionalmente le scuole per la giornata di oggi. Analogo provvedimento \u00e8 stato adottato anche in altri centri del reggino. Nel vibonese, l\u2019Anas comunica che, a causa di una frana,&nbsp;\u00e8 stato chiuso provvisoriamente al traffico, in entrambe le direzioni, un tratto della strada statale 182 &#8220;delle Serre Calabre&#8221;&nbsp;al km 39,100, in localit\u00e0 Sorianello ed&nbsp;Il traffico \u00e8 temporaneamente deviato sulla viabilit\u00e0 locale.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #0000ff;\"><strong>FOTO: CEDE TRATTO DI STRADA TRA FALERNA E GIZZERIA SULLA STATALE 18<\/strong><\/span><\/p>\n<\/p>\n<p>&nbsp;<img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"images\/gallery_new\/Marco2\/Falerna%20Crollo2.jpg\" alt=\"Falerna Crollo2\" title=\"\"><\/p>\n<p><img decoding=\"async\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"images\/gallery_new\/Marco2\/Falerna%20Crollo3.jpg\" alt=\"Falerna Crollo3\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; La statale 18, Tirrena Inferiore, \u00e8 stata chiusa a causa di un allagamento.<\/p>\n","protected":false},"author":22,"featured_media":42246,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-42245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/42245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=42245"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/42245\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/42246"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=42245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=42245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=42245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}