{"id":42396,"date":"2015-04-02T04:38:34","date_gmt":"2015-04-02T02:38:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/consorzio-asi-cosenza-gdf-sequestra-beni-a-tommasi-e-frasca\/"},"modified":"2023-01-17T12:33:51","modified_gmt":"2023-01-17T11:33:51","slug":"19016-consorzio-asi-cosenza-gdf-sequestra-beni-a-tommasi-e-frasca","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/19016-consorzio-asi-cosenza-gdf-sequestra-beni-a-tommasi-e-frasca\/","title":{"rendered":"Consorzio Asi Cosenza: truffa, falso e abuso d&#8217;ufficio la Finanza sequestra i beni Tommasi e Frasca"},"content":{"rendered":"<p>COSENZA &#8211; L&#8217;ente dovrebbe promuovere, attraverso dei bandi, lo sviluppo industriale nella provincia di Cosenza.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La guardia di finanza ha sequestrato beni per un valore di circa 110.000 euro all&#8217;ex presidente e all&#8217;ex direttore generale del Consorzio Asi di Cosenza, rispettivamente l&#8217;ex assessore regionale Diego Tommasi, prima in quota Verdi e ora in Forza Italia, e l&#8217;architetto Stefania Frasca. Si tratta di un sequestro per equivalente, disposto nell&#8217;ambito di un&#8217;inchiesta della Procura di Cosenza, guidata da Dario Granieri, in cui Tommasi e Frasca sono indagati per i reati di truffa, falso e abuso d&#8217;ufficio in relazione alla gestione delle spese dell&#8217;Asi. Le indagini, ancora in corso, sono iniziate nel 2013. Tra i beni sequestrati ci sono un immobile e diversi conti correnti bancari. Dalle indagini condotte dai finanzieri sarebbe emerso un consistente rimborso di spese non documentate e anche un aumento dei compensi destinati all&#8217;ex direttore.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; L&#8217;ente dovrebbe promuovere, attraverso dei bandi, lo sviluppo industriale nella provincia di Cosenza.<\/p>\n","protected":false},"author":22,"featured_media":42397,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-42396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/42396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=42396"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/42396\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/42397"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=42396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=42396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=42396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}