{"id":42665,"date":"2015-04-13T04:14:48","date_gmt":"2015-04-13T02:14:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/immigrazione-nave-dattilo-attraccata-a-reggio-calabria\/"},"modified":"2023-01-17T12:34:09","modified_gmt":"2023-01-17T11:34:09","slug":"19157-immigrazione-nave-dattilo-attraccata-a-reggio-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/19157-immigrazione-nave-dattilo-attraccata-a-reggio-calabria\/","title":{"rendered":"Salvate seicento persone a largo del canale di Sicilia, nave attraccata a Reggio Calabria"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; Al momento pare che i migranti a bordo non siano in condizioni di salute particolarmente precarie.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La motovedetta militare Dattilo \u00e8 giunta ieri pomeriggio nel porto di Reggio Calabria con a bordo circa 600 migranti salvati nelle ore scorse nel canale di Sicilia. A bordo della nave sono presenti uomini di varie nazionalit\u00e0 provenienti dal Corno d&#8217;Africa in prevalenza Somalia ed Eritrea. Al momento dello sbarco i migranti saranno sottoposti alle prime cure sanitarie da parte del personale medico presente sul posto. La quasi totalit\u00e0 dei migranti sar\u00e0 inviata in centri di accoglienza di varie regioni del centro-nord e solo una parte rester\u00e0 a Reggio Calabria.<\/p>\n<p>&nbsp;<\/p>\n<p>Il leader del movimento Diritti Civili, Franco Corbelli, in una nota, sottolinea il &#8220;vero volto di una regione, la Calabria, che, pur alle prese con una grave crisi economica e con drammatici problemi, continua ad accogliere con generosit\u00e0 e umanit\u00e0 gli immigrati che rischiando la vita cercano di arrivare in Italia, fuggendo dalla miseria, dalle guerre e dalle persecuzioni e spesso purtroppo trovando la morte in tragici sbarchi&#8221;.<strong> Corbelli chiede che &#8220;la Calabria non venga lasciata da sola, ma adeguatamente supportata, dal Governo e dall&#8217;Unione Europea&#8221;.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Quello che sta accadendo anche in queste ultime ore, la nuova nave con il maxi sbarco previsto a Reggio, con altre centinaia di migranti &#8211; afferma Corbelli &#8211; \u00e8 la conferma del ruolo centrale che la Calabria continua ad avere per affrontare il dramma dell&#8217;immigrazione.<strong> La Calabria, e siamo orgogliosi per questo, continua ad essere assoluta e generosa protagonista dell&#8217;accoglienza ai poveri migranti del mondo.<\/strong> Continua a mostrare il suo vero volto, che non \u00e8 certamente quello di qualche isolata protesta anti-immigrati&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Al momento pare che i migranti a bordo non siano in condizioni di salute particolarmente precarie.<\/p>\n","protected":false},"author":22,"featured_media":42666,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-42665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/42665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=42665"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/42665\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/42666"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=42665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=42665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=42665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}