{"id":4288,"date":"2012-09-26T11:27:01","date_gmt":"2012-09-26T09:27:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=4288"},"modified":"2023-01-17T13:37:36","modified_gmt":"2023-01-17T12:37:36","slug":"1399-crotone-giovani-giornalisti-crescono-nel-nome-di-enzo-biagi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/1399-crotone-giovani-giornalisti-crescono-nel-nome-di-enzo-biagi\/","title":{"rendered":"Crotone, giovani giornalisti crescono nel nome di Enzo Biagi"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>CROTONE &#8211;<\/strong> Maestro di sapere, cultura e giornalismo. Gli alunni delle scuole elementari e medie della citt\u00e0 si preparano a diventare \u201ccronisti\u201d e lo faranno nel nome di un grande del giornalismo nazionale: Enzo Biagi. L\u2019Amministrazione Comunale ha istituito il premio \u201cNati per scrivere \u2013 Enzo Biagi\u201d dedicato al giornalista scritto scomparso nel novembre 2007.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">\u00abIl Comune di Crotone ha inteso intitolare il premio ad Enzo Biagi considerate anche le sue grandi doti di divulgatore ed intende coinvolgere i giovani studenti delle scuole della citt\u00e0 di Crotone in un percorso di conoscenza del mondo della comunicazione pubblica ed istituzionale attraverso l\u2019incontro oltre che con le istituzioni anche con i rappresentanti del mondo dell\u2019informazione come giornalisti, pubblicisti, esperti della comunicazione dichiara il vice sindaco ed assessore alla Pubblica Istruzione Teresa Cortese. Lo scorso anno l\u2019Amministrazione Comunale var\u00f2 l\u2019iniziativa \u201cil gioved\u00ec dei ragazzi\u201d, un giorno in cui la casa comunale diveniva ufficialmente dei ragazzi delle scuole elementari e medie della citt\u00e0. Nel periodo gennaio\/giugno 2012 l\u2019iniziativa ha visto la partecipazione di oltre ottocento alunni che hanno accolto positivamente questa forma innovativa di dialogo con gli amministratori. Ci ha particolarmente e piacevolmente sorpreso &#8211; aggiunge &#8211; l\u2019invio da parte dei ragazzi di centinaia di pensieri, disegni, poesie, di proposte di cittadinanza attiva. Un segnale di grande voglia di dialogo e di comunicazione da parte di questi giovani cittadini. Su questi presupposti l\u2019amministrazione comunale ha impostato i prossimi incontri con i giovani alunni sui temi della informazione e della comunicazione ed ha istituito il premio intitolato ad Enzo Biagi. Nel corso degli incontri nella casa comunale, che saranno concordati con i dirigenti scolastici, gli alunni potranno oltre che incontrare gli amministratori e dialogare con loro conoscere le tecniche di comunicazione e di giornalismo con l\u2019ausilio di esperti del settore. Successivamente i ragazzi saranno invitati a diventare a loro volta cronisti ed a descrivere la citt\u00e0 ed i suoi principali avvenimenti inviando i propri elaborati al Comune di Crotone. A tutte le scuole sar\u00e0 riconosciuto un attestato di partecipazione ed inoltre gli articoli redatti dai giovani \u201cgiornalisti\u201d saranno raccolti e pubblicati in un volume a cura dell\u2019amministrazione comunale\u00bb. Il Comune ha interpellato le figlie del compianto giornalista, Bice e Carla, le quali hanno espresso apprezzamento per l\u2019iniziativa. \u00abHo ricevuto con grande piacere la comunicazione di Bice Biagi. La comunit\u00e0 di Crotone \u00e8 onorata di ricordare un grande giornalista e soprattutto un grande uomo e di poterlo fare attraverso una iniziativa che coinvolge i ragazzi di questa citt\u00e0 &#8211; dichiara il sindaco Peppino Vallone. Saremmo lieti &#8211; conclude &#8211; della presenza delle signore Biagi in occasione dell\u2019avvio delle attivit\u00e0 del premio intitolato al loro illustre genitore\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE &#8211; Maestro di sapere, cultura e giornalismo. Gli alunni delle scuole elementari e medie della citt\u00e0 si preparano a diventare \u201ccronisti\u201d e lo faranno nel nome di un grande del giornalismo nazionale: Enzo Biagi. L\u2019Amministrazione Comunale ha istituito il premio \u201cNati per scrivere \u2013 Enzo Biagi\u201d dedicato al giornalista scritto scomparso nel novembre 2007.<\/p>\n","protected":false},"author":22,"featured_media":4289,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18,5],"tags":[],"class_list":["post-4288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=4288"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4288\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/4289"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=4288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=4288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=4288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}