{"id":42964,"date":"2015-04-21T03:29:17","date_gmt":"2015-04-21T01:29:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ruba-auto-e-moto-carabinieri-arrestano-un-marocchino-di-25-anni\/"},"modified":"2023-01-17T12:34:29","modified_gmt":"2023-01-17T11:34:29","slug":"19311-ruba-auto-e-moto-carabinieri-arrestano-un-marocchino-di-25-anni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/19311-ruba-auto-e-moto-carabinieri-arrestano-un-marocchino-di-25-anni\/","title":{"rendered":"Ruba auto e moto, carabinieri arrestano un marocchino nel centro storico"},"content":{"rendered":"<p>COSENZA &#8211; I carabinieri di Cosenza hanno arrestato in flagranza del reato di furto un 25enne di origine marocchina, T.Z.<\/p>\n<p>  <!--more-->  <\/p>\n<p>I militari avevano notato uomo, pregiudicato, &nbsp;che, alle 3 del mattino in localit\u00e0 Paparelle, viaggiava a bordo di una Fiat Punto trasportando all\u2019interno del mezzo una moto kawasaki di grossa cilindrata. Insospettiti hanno cos\u00ec intimato l\u2019alt al mezzo ma il conducente, alla vista della paletta dei militari, ha accelerato ed \u00e8 cos\u00ec scaturito un inseguimento nella zona del centro storico bruzio. Infine, vistosi in trappola il fuggitivo si \u00e8 fermato ed ha tentato di dileguarsi a piedi ma \u00e8 stato prontamente raggiunto dai militari che lo hanno arrestato e condotto in caserma. I successivi accertamenti hanno permesso di appurare che sia la Fiat Punto che la moto erano oggetto di un furto consumato pochi istanti prima, e che l\u2019arrestato non era nemmeno in possesso della patente di guida, mai conseguita. La refurtiva \u00e8 stata riconsegnata ai legittimi proprietari mentre l\u2019uomo \u00e8 stato accompagnato presso il proprio domicilio in attesa del rito direttissimo ed \u00e8 stato anche denunciato a piede libero per il reato di resistenza a pubblico ufficiale e guida senza patente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; I carabinieri di Cosenza hanno arrestato in flagranza del reato di furto un 25enne di origine marocchina, T.Z.<\/p>\n","protected":false},"author":19,"featured_media":42965,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-42964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/42964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=42964"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/42964\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/42965"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=42964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=42964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=42964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}