{"id":43607,"date":"2015-05-12T11:51:34","date_gmt":"2015-05-12T09:51:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/secondo-un-indagine-un-lavoratore-del-sud-costa-450-in-piu-di-uno-del-nord\/"},"modified":"2023-01-17T12:35:11","modified_gmt":"2023-01-17T11:35:11","slug":"19652-secondo-un-indagine-un-lavoratore-del-sud-costa-450-in-piu-di-uno-del-nord","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/19652-secondo-un-indagine-un-lavoratore-del-sud-costa-450-in-piu-di-uno-del-nord\/","title":{"rendered":"Secondo un&#8217;indagine un lavoratore del Sud costa 450 euro in pi\u00f9 di uno del Nord"},"content":{"rendered":"<p>ROMA &#8211; Tra il 2011 e il 2014 le modifiche dell&#8217;Irap hanno ridotto il costo del lavoro al Centro-Nord di 2.592 euro e al Sud di 2.263.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Il dato emerge dallo studio &#8220;Modifiche alla disciplina dell&#8217;Irap ed effetti sul costo del lavoro e sul cuneo fiscale: un raffronto territoriale&#8221; di Gaetano Stornaiuolo e Salvatore Villani di prossima pubblicazione sulla &#8220;Rivista Economica del Mezzogiorno&#8221;, trimestrale della Svimez. Secondo i due studiosi, <strong>la minore efficacia delle misure fiscali continua e si aggrava nel 2015, con una riduzione del costo del lavoro di 8.362 euro al Centro-Nord e di 8.144 al Sud<\/strong>. Rispetto a un lavoratore assunto a tempo indeterminato al Centro-Nord negli ultimi quattro anni, quello del Sud costa circa 450 euro in pi\u00f9. Sud che viene privato di 3,5 miliardi di euro prelevati dal Piano di Azione e Coesione per finanziare gli sgravi contributivi anche ad aziende del Centro-Nord.<\/p>\n<p>&nbsp;<\/p>\n<p>A fronte di una retribuzione lorda media di 30.137 euro nel Centro-Nord e di 25.488 euro nel Mezzogiorno, evidenzia ancora lo studio, <strong>dal 2011 al 2014 il costo del lavoro per le imprese al lordo Irap \u00e8 sceso in entrambe le ripartizioni, ma con andamenti differenti e penalizzanti per il Sud<\/strong>. Nel 2011 nel Centro-Nord il costo azienda di un lavoratore medio ammontava a 42.865 euro, con un cuneo fiscale di 12.728 euro; tre anni dopo, nel 2014, a fronte della stessa retribuzione lorda media, il costo del lavoro di un nuovo assunto a tempo indeterminato e&#8217; stato pari a 40.273 euro e il cuneo fiscale \u00e8 sceso a 10.136 euro. Costo del lavoro e cuneo fiscale sono quindi diminuiti di 2.592 euro. Dinamica simile al Sud, ma con riduzioni complessive minori rispetto a quelle ottenute dalle imprese del Centro-Nord: nel 2011 il costo azienda di un lavoratore medio ammontava a 36.198 euro, con un cuneo fiscale di 10.710 euro; tre anni dopo, nel 2014, a fronte della stessa retribuzione lorda media, il costo del lavoro per i nuovi assunti e&#8217; diventato pari a 33.935 euro, e il cuneo fiscale e&#8217; sceso a 8.447 euro. Rispetto ai 2.592 euro del Centro-Nord, al Sud la riduzione del costo del lavoro e del cuneo fiscale \u00e8 stata di 2.263 euro, cio\u00e8 329 euro in meno. <strong>Per ogni nuovo lavoratore assunto a tempo indeterminato entro il 31 dicembre 2015, inoltre, l&#8217;ultima Legge di Stabilita&#8217; ha previsto un ulteriore e forte abbattimento del costo del lavoro e del cuneo fiscale<\/strong>: 8.362 euro al Centro- Nord, 8.144 euro per le imprese del Mezzogiorno, con una differenza, penalizzante per il Sud, di 218 euro.<\/p>\n<p>&nbsp;<\/p>\n<p>I vantaggi fiscali Irap per le imprese (cioe&#8217; la riduzione dell&#8217;Irap determinata dalle agevolazioni fiscali) seguono lo stesso andamento del costo del lavoro e del cuneo fiscale. Nel 2011 nel Mezzogiorno il vantaggio fiscale medio e&#8217; stato pari a 425 euro per azienda, oltre il doppio del Centro-Nord (179 euro). Negli anni successivi le deduzioni crescono in entrambe le ripartizioni, riducendo il distacco: <strong>nel 2014 la deduzione media Irap per le imprese del Sud e&#8217; di 1.151 euro, 928 al Centro-Nord<\/strong>. Nel 2015, il sorpasso: il Sud si ferma a 1.192 euro, il Centro-Nord sale a 1.245. Rispetto quindi ai provvedimenti degli anni 2012 e 2013, che contenevano vantaggi Irap per le aree piu&#8217; deboli, le agevolazioni fiscali contenute nelle ultime leggi di stabilita&#8217; del 2014 e del 2015 penalizzano le imprese del Sud: a parita&#8217; di lavoratore da assumere a tempo indeterminato, per un imprenditore diventa piu&#8217; conveniente al Centro-Nord piuttosto che al Sud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; Tra il 2011 e il 2014 le modifiche dell&#8217;Irap hanno ridotto il costo del lavoro al Centro-Nord di 2.592 euro e al Sud di 2.263.<\/p>\n","protected":false},"author":22,"featured_media":43608,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-43607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/43607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=43607"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/43607\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/43608"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=43607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=43607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=43607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}