{"id":43748,"date":"2015-05-17T04:20:06","date_gmt":"2015-05-17T02:20:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/presentazione-volume-territorio-violato\/"},"modified":"2023-01-17T12:35:20","modified_gmt":"2023-01-17T11:35:20","slug":"19723-presentazione-volume-territorio-violato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/19723-presentazione-volume-territorio-violato\/","title":{"rendered":"&#8221;Il territorio violato: paesaggio, territorio e criticit\u00e0 sociali&#8221;, domani presentazione del volume di Alberto Panuccio"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; Domani alle 9:30 presso l\u2019Aula Seminari del Dipartimento di Agraria, il Prof. Avv. Alberto Panuccio (presidente Ordine degli Avvocati di Reggio Calabria) presenter\u00e0 il volume \u201cIl territorio violato: paesaggio, territorio e criticit\u00e0 sociali\u201d.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Il libro nasce dall&#8217;intreccio di tre differenti culture che si incontrano per affrontare un unico tema: il paesaggio, che Salvatore Settis definisce &#8220;il grande malato italiano&#8221;.<strong> La ragione che ha spinto Bruno M. Bilotta e Roberto Saija a confrontarsi proprio sul paesaggio \u00e8 da ricercare nel diverso spirito che anima sociologi, giuristi ed economisti nel trovare soluzioni, cure efficaci contro i mali che lo affliggono<\/strong>, affinch\u00e9 esso non venga definitivamente deturpato dall&#8217;incuria e dagli interessi economici. Si \u00e8 detto, infatti, che il ventesimo secolo ha segnato gravemente il paesaggio italiano modificandolo strutturalmente fino quasi a distruggerlo. Il libro che i curatori propongono all&#8217;attenzione della Comunit\u00e0 accademica e professionale vuole rappresentare, invece, un segnale positivo, dimostrando che l&#8217;economia non sempre \u00e8 nemica della natura ma attraverso le regole \u00e8 possibile che costituisca occasione di stimolo verso una sua rafforzata protezione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Domani alle 9:30 presso l\u2019Aula Seminari del Dipartimento di Agraria, il Prof. Avv. Alberto Panuccio (presidente Ordine degli Avvocati di Reggio Calabria) presenter\u00e0 il volume \u201cIl territorio violato: paesaggio, territorio e criticit\u00e0 sociali\u201d.<\/p>\n","protected":false},"author":22,"featured_media":43749,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-43748","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/43748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=43748"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/43748\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/43749"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=43748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=43748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=43748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}