{"id":4434,"date":"2012-09-27T11:51:46","date_gmt":"2012-09-27T09:51:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=4434"},"modified":"2023-01-17T13:37:44","modified_gmt":"2023-01-17T12:37:44","slug":"1473-infinito-condanna-per-la-toga-sporca-4-anni-per-giusti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/1473-infinito-condanna-per-la-toga-sporca-4-anni-per-giusti\/","title":{"rendered":"Infinito, condanna per la toga &#8220;sporca&#8221;: 4 anni per Giusti"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>REGGIO CALABRIA &#8211;<\/strong> Toga &#8220;sporca&#8221;. Giancarlo Giusti, ex giudice in servizio presso il Tribunale di palmi, travolto dall&#8217;inchiesta giudiziaria &#8220;Infinito&#8221;, coordinata dalla Dda di Milano, su un intreccio tra la giustizia &#8220;corrotta&#8221; e la &#8216;ndrangheta, \u00e8 stato condannato a quattro anni di reclusione e a cinque anni d&#8217;interdizione dai pubblici uffici. Nonch\u00e8 la sospensione ddalla magistratura, decisa dal Csm subito dopo il suo arresto. <\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">E&#8217; questo il verdetto di condanna, pesantissima, emesso dal gup, nel corso del processo celebrato con il rito abbreviato. L&#8217;ex giudice, soapeso dsalla magistratura all&#8217;indomani del terremoto giudiziario, \u00e8 stato accusato di corruzione aggravata dalla finalit\u00e0 mafiosa. Secondo l&#8217;impianto accusatorio, Giancarlo Giusti, approfittando della sua funzione avrebbe utilizzato la sua toga per ricevere dal boss Giulio lampada, elemento di picco della &#8216;ndrangheta calabrese, radicata a Milano. Secondo i giudici di Milano, il magistrato sospeso, avrebbe ricevuto dal boss e dai suoi fiancheggiatori, come gesto di ringraziamento, anche viaggi, appuntamenti con escort di lusso e vacanze in hotel di alto livello. Oltre a Giusti, sono stati condannati anche Domenico Gattuso (6 anni) e l&#8217;avvocato Vincenzo Minasi (4 anni e 4 mesi). Stando alle indagini del procuratore aggiunto Ilda Boccassini e dei pm Storari e Alessandra Dolci, l&#8217;avvocato Vincenzo Minasi era uno dei rappresentanti della &#8220;zona grigia&#8221; della &#8216;ndrangheta. Giusti \u2013 45 anni, dal 2001 giudice delle esecuzioni immobiliari a Reggio Calabria, dal 2010 gip a Palmi e poi sospeso dal Csm con l&#8217;arresto \u2013 sarebbe stato invece, stando alle indagini, a \u00ablibro paga\u00bb della &#8216;ndrangheta. La mafia calabrese dei Lampada, secondo l&#8217;accusa, oltre a offrirgli &#8221;affari&#8221;, avrebbe appagato quella che nell&#8217;ordinanza di custodia cautelare del gip Giuseppe Gennari era stata definita una vera e propria \u00abossessione per il sesso\u00bb, facendogli trovare \u00abprostitute\u00bb in alberghi di lusso milanesi, con le spese di soggiorno e di viaggio comprese nel prezzo della corruzione. Il giudice venne arrestato lo scorso marzo per corruzione aggravata dalla finalita&#8217; mafiosa in uno dei filoni dell&#8217;inchiesta sulla cosca dei Valle-Lampada. Il direttore dell&#8217;hotel milanese &#8220;Brun&#8221; \u2013 uno degli alberghi frequentati da Giusti \u2013 era invece accusato di favoreggiamento personale. Il magistrato poi si sarebbe messo a disposizione in particolare di Giulio Lampada (a processo con rito ordinario assieme ad altri). Con Lampada sarebbe stato \u00absocio occulto\u00bb di un societ\u00e0 off-shore \u00abamministrata\u00bb dall&#8217;avvocato Minasi (le cui dichiarazioni ai pm hanno fornito riscontri) e che si aggiudic\u00f2 \u00ab5 lotti immobiliari\u00bb all&#8217;asta, nel marzo 2009, del valore di circa 300mila. IL PROFILO: Il ritratto che i giudici della Dda di Milano fanno sul gip di Palmi \u00e8 inquietante. Dalle carte emerge che Giancarlo Giusti \u00e8 \u00abossessionato dal sesso e dalla bella vita\u00bb. Il giudice per le indagini preliminari di Milano Giuseppe Gennari, firmatario dell&#8217;ordinanza di custodia cautelare nei confronti di Giusti, dopo aver esaminato il diario telematico del giudice, scrive che &#8220;Il quadro complessivo che emerge \u00e8 deprimente&#8221;. Le pagine di diario riportate sono solo una quota parziale (e quelle mancanti non sono certo meglio). Ma tutte propongono gli stessi temi ricorrenti: ossessione per il sesso, per lo pi\u00f9 a pagamento, esigenze economiche legate ad un tenore di vita sicuramente elevato, spasmodica ricerca di occasioni di guadagno parallele in operazioni immobiliari e di varia altra natura. Giusti appare come personaggio fragilissimo e, per costume di vita, esposto alla tentazione di condotte illecite. E quindi \u00e8 comprensibile, dato gravissimo in termini di pericolosit\u00e0 sociale &#8211; continua il gip &#8211; come egli ceda immediatamente ai richiami di Lampada che offre da subito donne pagate, divertimenti, affari, conoscenze utili. Stupefacente \u00e8 la rapidita&#8217; con cui Giusti si unisce a Lampada. A fine settembre 2008 i due si conoscono, il 6-8 ottobre Giusti e&#8217; gia&#8217; a Milano nelle braccia di prostitute (e quindi \u00e8 gi\u00e0 compromesso con Lampada). Il tutto nel contesto di un rapporto personale assolutamente intimo, come attestato dalle numerose telefonate intercorse tra i due\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Toga &#8220;sporca&#8221;. Giancarlo Giusti, ex giudice in servizio presso il Tribunale di palmi, travolto dall&#8217;inchiesta giudiziaria &#8220;Infinito&#8221;, coordinata dalla Dda di Milano, su un intreccio tra la giustizia &#8220;corrotta&#8221; e la &#8216;ndrangheta, \u00e8 stato condannato a quattro anni di reclusione e a cinque anni d&#8217;interdizione dai pubblici uffici. Nonch\u00e8 la sospensione ddalla [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":4435,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16,5],"tags":[],"class_list":["post-4434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=4434"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4434\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/4435"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=4434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=4434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=4434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}