{"id":44445,"date":"2015-06-09T15:19:30","date_gmt":"2015-06-09T13:19:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/unaltra-morte-sulla-statale-106-vittima-una-donna-emigrata-al-nord-che-attraversava-la-strada\/"},"modified":"2023-01-17T12:35:59","modified_gmt":"2023-01-17T11:35:59","slug":"41668-unaltra-morte-sulla-statale-106-vittima-una-donna-emigrata-al-nord-che-attraversava-la-strada","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/41668-unaltra-morte-sulla-statale-106-vittima-una-donna-emigrata-al-nord-che-attraversava-la-strada\/","title":{"rendered":"Marito e moglie investiti sulla statale 10, travolti da una moto"},"content":{"rendered":"<h4>I due sarebbero stati travolti da una motocicletta che non \u00e8 riuscita a scansarli.\u00a0<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CATANZARO\u00a0&#8211; Una persona \u00e8 morta e due sono rimaste ferite in un incidente stradale avvenuto questo pomeriggio a Davoli, in provincia di Catanzaro, sulla strada statale 106. Secondo quanto ricostruito dai carabinieri, la vittima \u00e8 una donna che stava attraversando la strada insieme al marito, rimasto ferito. Anche il motociclista che li ha investiti \u00e8\u00a0stato soccorso e ricoverato a causa delle gravi ferite riportate nello scontro anche se, per ora, pare non sia in pericolo di vita. La statale 106 \u00e8 stata chiusa al traffico per consentire le operazioni di soccorso e i rilievi da parte dei carabinieri. La donna rimasta uccisa nell&#8217;incidente aveva 61 anni ed era residente ad Erba, in provincia di Como.<strong> Il marito, anch&#8217;egli sessantunenne, \u00e8 ricoverato in prognosi riservata per le gravi ferite riportate.<\/strong> Entrambi sono originari della provincia di Catanzaro ed erano da poco tempo rientrati in Calabria.<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;uomo che guidava la motocicletta che ha provocato l&#8217;incidente \u00e8 un commerciante di Davoli che, secondo gli accertamenti dei carabinieri, stava percorrendo la statale 106 in direzione sud. <strong>La coppia, invece, stava attraversando la strada per recarsi, probabilmente, in un bar, nel centro abitato del paese.<\/strong> Secondo quanto accertato dai militari, il corpo della signora, \u00e8 stato scaraventato dopo la collisione ad alcuni metri di distanza. La donna morta sul colpo dopo l&#8217;impatto con la motocicletta si chiamava Maria Grillone ed era rientrata in provincia di Catanzaro insieme al marito Sandro Fusi. I due avevano vissuto per anni in provincia di Como, quindi avevamo deciso di rientrare nel Soveratese, considerato che le famiglie sono originarie di Vallefiorita. L&#8217;uomo lotta tra la vita e la morte Anell&#8217;ospedale di Catanzaro, dove e&#8217; stato trasportato dall&#8217;elicottero dopo l&#8217;impatto violento con la motocicletta.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I due sarebbero stati travolti da una motocicletta che non \u00e8 riuscita a scansarli.\u00a0<\/p>\n","protected":false},"author":22,"featured_media":44446,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-44445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/44445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=44445"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/44445\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/44446"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=44445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=44445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=44445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}