{"id":44777,"date":"2015-06-18T13:46:39","date_gmt":"2015-06-18T11:46:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/a-catanzaro-un-weekend-dedicato-allippica-170-partecipanti-in-gara\/"},"modified":"2023-01-17T12:36:19","modified_gmt":"2023-01-17T11:36:19","slug":"42844-a-catanzaro-un-weekend-dedicato-allippica-170-partecipanti-in-gara","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/42844-a-catanzaro-un-weekend-dedicato-allippica-170-partecipanti-in-gara\/","title":{"rendered":"A Catanzaro un weekend dedicato all&#8217;ippica: 170 partecipanti in gara"},"content":{"rendered":"<h4><strong>La tre giorni \u00e8 organizzata dalla\u00a0Federazione nazionale sport equestri e dal ministero delle Politiche agricole alla Valle dei\u00a0Mulini.<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; Il concorso ippico nazionale riservato a cavalli italiani, con l\u2019intento anche di valorizzare gli\u00a0allevamenti del nostro territorio, si svolger\u00e0 da domani fino\u00a0a domenica 21 giugno nella\u00a0struttura sportiva dell\u2019amministrazione provinciale di Catanzaro. <strong>Un grande successo di\u00a0iscritti: 170 in gara provenienti da Calabria, Puglia, Sicilia e Basilicata<\/strong>. Il concorso\u00a0prevede lo svolgimento di 18 gare al giorno, a partire dalle 11,00 di domani. Il Centro ippico rappresenta una realt\u00e0 territoriale di prestigio per gli operatori e per gli\u00a0appassionati del settore dell\u2019equitazione, e si \u00e8 ben distinto a livello nazionale con\u00a0l\u2019organizzazione di numerosi e importanti concorsi.<\/p>\n<p>&nbsp;<\/p>\n<p>Grazie alla realizzazione delle opere di\u00a0completamento, il centro ippico \u201cValle dei\u00a0Mulini\u201d sar\u00e0 dotato di strutture e servizi finalizzati al miglioramento dell\u2019opera esistente ed\u00a0alla sua funzionalit\u00e0.\u00a0Completate le principali strutture da realizzare anche per la fruibilit\u00e0 del centro in vista\u00a0dell\u2019importante concorso in programma per domani, che hanno comportato l\u2019aggiunta di nuova volumetria con la copertura del campo di gara e la realizzazione dei box fissi per i\u00a0cavalli. <strong>La struttura di recente realizzazione comprende 18 box per stabulazione mobile\u00a0cavalli, e 5 locali destinati rispettivamente a lavaggio, asciugatoio, mascalcia, selleria e\u00a0locale per l\u2019isolamento degli animali infetti<\/strong>. In prossimit\u00e0 delle scuderie e pi\u00f9 precisamente\u00a0sul lato nord delle stesse e del fabbricato pronto soccorso sono stati installati di recente dei\u00a0box in legno e acciaio, smontabili, per il ricovero dei cavalli.<\/p>\n<p>&nbsp;<\/p>\n<p>Tra gli interventi prioritari per rendere l\u2019impianto\u00a0fruibile per la tre giorni di concorso in programma questo fine settimana, anche la\u00a0realizzazione della copertura del campo di prova e delle tribune.\u00a0\u201cNel corso degli anni la Valle dei Mulini \u2013 ha affermato il presidente Bruno &#8211; ha ospitato importanti concorsi regionali e\u00a0nazionali dando lustro alla citt\u00e0 di Catanzaro e alla Provincia. Con la realizzazione di\u00a0queste opere di completamento <strong>di certo la struttura sportiva della nostra amministrazione\u00a0riuscir\u00e0 ad occupare una posizione primaria nei circuiti ippici nazionali ed esteri<\/strong> con\u00a0conseguenti benefici per il territorio provinciale e regionale, con una importante ricaduta\u00a0economico nell\u2019indotto turistico e dell\u2019accoglienza. Le\u00a0manifestazioni di equitazione non hanno infatti solo un&#8217;importante valenza sportiva, ma\u00a0possono rappresentare un volano per l\u2019economia sul territorio, visto che durante i\u00a0concorsi arrivano a Catanzaro centinaia di cavalieri con gli staff, le famiglie e un grande\u00a0seguito di appassionati&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cIl concorso che si terr\u00e0 alla Valle dei Mulini rappresenta una gara importante,- ha aggiunto il presidente della Fise Cardona &#8211; che permetter\u00e0 di lanciare a livello nazionale la\u00a0qualit\u00e0 impiantistica e tecnica dei nostri istruttori e dei nostri cavalli. \u00a0Voglio ringraziare il presidente della Provincia Enzo Bruno e\u00a0l\u2019intera amministrazione per la fiducia riservata alla nostra federazione. La buona politica attenta e al servizio dello\u00a0sport \u00e8 un elemento di ricchezza per il nostro territorio. <strong>Mi auguro che i lavori di\u00a0ampliamento del centro ippico vengano completati al pi\u00f9 presto per rendere fruibile\u00a0l\u2019impianto anche ad altre discipline sportive<\/strong>\u201d. Il presidente Bruno e il sindaco di Catanzaro, insieme\u00a0alle autorit\u00e0 civili e militari, saranno presenti alle premiazioni in programma per\u00a0sabato pomeriggio alle 16,00.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tre giorni \u00e8 organizzata dalla\u00a0Federazione nazionale sport equestri e dal ministero delle Politiche agricole alla Valle dei\u00a0Mulini.<\/p>\n","protected":false},"author":22,"featured_media":44778,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-44777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/44777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=44777"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/44777\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/44778"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=44777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=44777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=44777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}