{"id":45175,"date":"2015-06-30T13:17:24","date_gmt":"2015-06-30T11:17:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ambiente-a-cotronei-si-progetta-il-ripopolamento-ittico-del-lago-ampollino\/"},"modified":"2023-01-17T12:36:46","modified_gmt":"2023-01-17T11:36:46","slug":"43923-ambiente-a-cotronei-si-progetta-il-ripopolamento-ittico-del-lago-ampollino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/43923-ambiente-a-cotronei-si-progetta-il-ripopolamento-ittico-del-lago-ampollino\/","title":{"rendered":"Ambiente, a Cotronei si progetta il ripopolamento ittico del lago Ampollino"},"content":{"rendered":"<h4><strong>Continua l\u2019attenzione dell\u2019Amministrazione Comunale di Cotronei e della societ\u00e0 A2A\u00a0sui temi ambientali.<\/strong> <!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COTRONEI (KR) &#8211; Dopo la positiva collaborazione fra i due soggetti nella realizzazione\u00a0della giornata ecologica del 27 giugno, un\u2019altra importante iniziativa viene calendarizzata: il ripopolamento del lago.\u00a0Nei giorni scorsi sono stati definiti i dettagli del piano di ripopolamento ittico del lago\u00a0Ampollino che la societ\u00e0 A2A dovr\u00e0 effettuare in seguito ai lavori di messa in sicurezza,\u00a0svolti nel bacino idrico nei mesi conclusivi dell&#8217;anno scorso. In un documento\u00a0indirizzato al Comune di Cotronei, il Responsabile degli Impianti Calabria di A2A,\u00a0scrive: &#8220;A seguito dei dovuti monitoraggi per la raccolta dei dati post-operam \u00e8 stato\u00a0redatto un piano di ripopolamento ittico. <strong>Dall&#8217;analisi dei dati \u00e8 stato possibile definire\u00a0specie, taglie e quantit\u00e0 necessaria ai fini del ripristino delle popolazioni ittiche&#8221;<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Il piano\u00a0di ripopolamento \u00e8 articolato negli anni compresi tra il 2015 e il 2017, e prevede\u00a0l&#8217;immissione di pesci nel lago in momenti differenti. Nell&#8217;anno in corso saranno immessi 3.000 kg di trota fario adulta (cm 20\/24), da immettere in tre step mensili di\u00a01.000 kg partendo dal mese di luglio. Per l&#8217;anno 2016, 2.000 kg di trota fario adulta (cm\u00a020\/24), da immettere in step mensili di 1.000 kg; e poi 100.000 esemplari di avannotti di\u00a0trota fario da immettere in un unico step. Infine, per l&#8217;anno 2017, 1.000 kg di trota fario\u00a0adulta da immettere in step mensili e 100.000 avannotti di trota fario da immettere in un\u00a0unico step.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cGi\u00e0 nella seconda decade del mese di luglio &#8211; commenta il sindaco di Cotronei Nicola\u00a0Belcastro &#8211; <strong>la societ\u00e0 che gestisce il bacino idrico e i relativi impianti, dunque, provveder\u00e0\u00a0a ripopolare il lago con specie ittiche autoctone<\/strong>, dando corso agli accordi che aveva\u00a0preso con il Comune di Cotronei in occasione dei lavori di manutenzione che avevano\u00a0portato al parziale svuotamento dell&#8217;Ampollino ed alla realizzazione delle manutenzioni\u00a0necessarie per garantire la sicurezza. Oltre a rilevare che le modalit\u00e0 operative\u00a0dell\u2019intervento di manutenzione sono state quelle meno invasive possibili, senza alcuna\u00a0operazione di fluitazione, ora si passa alla fase di rilancio e di ripopolamento.<\/p>\n<p>&nbsp;<\/p>\n<p>Nei\u00a0prossimi giorni concorderemo le modalit\u00e0 pi\u00f9 adatte alla prima azione da compiere nel\u00a0prossimo mese, rilevando che un ripopolamento di questa entit\u00e0 non si \u00e8 mai realizzato:\u00a0<strong>tre tonnellate di trote adulte verranno rilasciate nei prossimi mesi<\/strong> e nel triennio si\u00a0avranno rilasci per ben sei tonnellate di trote adulte e 200.000 avannotti. L\u2019attenzione per\u00a0il territorio e il seguire scrupolosamente ogni azione che riguarda la nostra realt\u00e0\u00a0producono anche risultati significativi, come questi\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continua l\u2019attenzione dell\u2019Amministrazione Comunale di Cotronei e della societ\u00e0 A2A\u00a0sui temi ambientali.<\/p>\n","protected":false},"author":22,"featured_media":45176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-45175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/45175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=45175"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/45175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/45176"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=45175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=45175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=45175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}