{"id":45286,"date":"2015-07-05T06:40:22","date_gmt":"2015-07-05T04:40:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/andrea-scanzi-a-cosenza-in-uno-spettacolo-sulla-vita-di-fabrizio-de-andre\/"},"modified":"2023-01-17T12:36:52","modified_gmt":"2023-01-17T11:36:52","slug":"44223-andrea-scanzi-a-cosenza-in-uno-spettacolo-sulla-vita-di-fabrizio-de-andre","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/44223-andrea-scanzi-a-cosenza-in-uno-spettacolo-sulla-vita-di-fabrizio-de-andre\/","title":{"rendered":"Andrea Scanzi a Cosenza in uno spettacolo sulla vita di Fabrizio De Andr\u00e8"},"content":{"rendered":"<h4><strong>Cultura, conoscenza e solidariet\u00e0: tre appuntamenti targati 5 Stelle a Cosenza il 6 e 7 luglio prossimi.<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA \u00a0&#8211; \u00c8 tutto pronto per il primo spettacolo in Calabria di Andrea Scanzi. Domani\u00a0alle 21.00 presso\u00a0l\u2019anfiteatro \u201cTieri\u201d di Castrolibero, andr\u00e0 in scena\u00a0lo spettacolo \u201cLe cattive strade\u201d.<strong> Il giornalista toscano\u00a0insieme al cantautore e attore Giulio Casale ripercorrer\u00e0 la carriera artistica del poeta e cantautore ligure\u00a0Fabrizio De Andr\u00e9<\/strong>. I cinquestelle cosentini arricchiranno l\u2019evento con la finalit\u00e0 benefica, infatti, con il\u00a0ricavato della serata saranno istituite delle borse di studio che saranno poi assegnate a ragazzi meritevoli,\u00a0ma in condizione di svantaggio economico.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019evento si arricchisce, per\u00f2, di ulteriori occasioni di confronto e iniziative. Nel pomeriggio di domani,\u00a0alle\u00a019.00, <strong>Andrea Scanzi sar\u00e0 in Piazza XI Settembre per la presentazione del suo ultimo romanzo \u201cLa vita \u00e8 un\u00a0ballo fuori tempo\u201d<\/strong>. L\u2019incontro sar\u00e0 accompagnato dall\u2019intervento del cittadino eletto al Senato Nicola\u00a0Morra e avr\u00e0 come moderatore il giornalista Emiliano Morrone.<\/p>\n<p>&nbsp;<\/p>\n<p>Il Meetup Cosenza, promotore dell\u2019evento e fautore della raccolta fondi legata allo spettacolo, rilancia per\u00f2\u00a0con un\u2019ulteriore iniziativa invitando tutti i cittadini a partecipare il marted\u00ec successivo alla <strong>passeggiata lungo il\u00a0corso del centro storico della citt\u00e0 insieme ad Andrea Scanzi<\/strong>. \u00a0Alle 10.00 i cinquestelle, accompagnati anche\u00a0dal portavoce Morra, risaliranno corso Telesio a partire da Piazza dei Valdesi per ammirare la bellezza\u00a0dimenticata della nostra citt\u00e0, troppo spesso abbandonata al degrado e all\u2019incuria.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Andrea Scanzi<\/strong> \u00e8 un apprezzato e stimato giornalista, autore teatrale e scrittore e racconter\u00e0 del percorso artistico del poeta e cantautore ligure. Alla sua narrazione si alterneranno le interpretazioni del cantautore e attore Giulio Casale, capace con il suo talento di personalizzare con rispetto e personalit\u00e0 il repertorio di Faber. Lo spettacolo sar\u00e0 arricchito da una particolare multimedialit\u00e0 grazie alla proiezione di filmati originali di Fabrizio De Andr\u00e8, estratti audio e foto rare.<br \/>\nI biglietti saranno in prevendita presso In Pirma Fila, la libreria Mondadori di Corso Mazzini e presso il locale Retr\u00f2 di via Tagliamento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cultura, conoscenza e solidariet\u00e0: tre appuntamenti targati 5 Stelle a Cosenza il 6 e 7 luglio prossimi.<\/p>\n","protected":false},"author":22,"featured_media":45287,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-45286","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/45286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=45286"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/45286\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/45287"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=45286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=45286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=45286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}