{"id":45317,"date":"2015-07-06T11:18:01","date_gmt":"2015-07-06T09:18:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/caldo-torrido-lasp-di-cosenza-attiva-un-piano-per-contenere-i-rischi\/"},"modified":"2023-01-17T12:36:55","modified_gmt":"2023-01-17T11:36:55","slug":"44312-caldo-torrido-lasp-di-cosenza-attiva-un-piano-per-contenere-i-rischi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/44312-caldo-torrido-lasp-di-cosenza-attiva-un-piano-per-contenere-i-rischi\/","title":{"rendered":"Caldo torrido,  l&#8217;Asp di Cosenza attiva un piano per contenere i rischi"},"content":{"rendered":"<h4>Previsti numero verde e informazioni su stili di vita da seguire.<!--more--><\/h4>\n<p>COSENZA\u00a0&#8211; L&#8217;Azienda sanitaria provinciale di Cosenza, per prevenire e contenere i rischi provocati dall&#8217;ondata di calore che ha investito l&#8217;Italia in questi giorni, ha predisposto un piano operativo integrato. Il piano intende tutelare i soggetti pi\u00f9 deboli, anziani, bambini e soggetti affetti da particolari patologie. Tra l&#8217;altro sar\u00e0 istituito un numero telefonico per ogni distretto a cui potersi rivolgere e saranno attivate informazioni sugli stili di vita da adottare.<\/p>\n<p>&nbsp;<\/p>\n<p>Acri\u2026\u2026\u2026\u20260984.914252\/914261<\/p>\n<p>Amantea\u2026\u2026\u2026.0982.429241<\/p>\n<p>Castrovillari\u2026.0981.25238\/25231\/25230<\/p>\n<p>Cariati\u2026..0983.9402223\/9402204<\/p>\n<p>Corigliano\u2026\u20260983.891806<\/p>\n<p>Cosenza\u2026\u2026\u2026\u2026\u20260984.813854<\/p>\n<p>Montalto Uffugo\u2026\u20260984.931074<\/p>\n<p>Paola\u2026\u20260982.5800222<\/p>\n<p>Praia a Mare\u2026\u2026.0985.73623\/73815<\/p>\n<p>Rende&#8230;&#8230;&#8230;&#8230; 0984.1659345<\/p>\n<p>Rogliano\u2026\u2026\u20260984.961001<\/p>\n<p>Rossano\u2026\u20260983.522424<\/p>\n<p>San Giovanni in Fiore\u2026\u2026 0984.9771244\/9771241<\/p>\n<p>San Marco Argentano\u20260984.512089 &#8211; 348\/8059582<\/p>\n<p>Trebisacce\u2026\u2026.0981 550228<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.asp.cosenza.it\/images\/prev_dipartimento\/calore_2015.pdf\" rel=\"noopener\">CLICCA QUI PER SCARICARE LA BROCHURE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previsti numero verde e informazioni su stili di vita da seguire.<\/p>\n","protected":false},"author":22,"featured_media":45318,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-45317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/45317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=45317"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/45317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/45318"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=45317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=45317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=45317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}