{"id":45355,"date":"2015-07-08T06:38:48","date_gmt":"2015-07-08T04:38:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/scandalo-rimborsopoli-il-presidente-della-giunta-accetta-linvito-a-dimettersi\/"},"modified":"2023-01-17T12:36:57","modified_gmt":"2023-01-17T11:36:57","slug":"44443-scandalo-rimborsopoli-il-presidente-della-giunta-accetta-linvito-a-dimettersi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/44443-scandalo-rimborsopoli-il-presidente-della-giunta-accetta-linvito-a-dimettersi\/","title":{"rendered":"Scandalo Rimborsopoli, il presidente della Giunta accetta l&#8217;invito a dimettersi"},"content":{"rendered":"<h4>Antonio Scalzo dopo vari tentennamenti e rifiuti ha finalmente deciso di abbandonare la propria poltrona.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA &#8211; &#8220;Domani mattina saranno protocollate alla Segreteria generale di palazzo Campanella le mie dimissioni dalla carica di presidente del Consiglio regionale della Calabria&#8221;. E&#8217; quanto afferma Antonio Scalzo in una nota. &#8220;La decisione di rimettere il mio mandato &#8211; prosegue &#8211; scaturisce da una valutazione personale e politica sul delicato momento che la Calabria sta attraversando. <strong>Ho deciso di dimettermi per compiere un gesto di responsabilit\u00e0 politica e per il rispetto delle istituzioni che mi ha sempre caratterizzato in ogni circostanza.<\/strong> Il cosiddetto caso &#8216;Rimborsopoli&#8217; mi riguarda in maniera marginale, molto marginale e comunque sono fiducioso che la mia vicenda sar\u00e0 interamente chiarita. Tuttavia ritengo che quanto pi\u00f9 alta \u00e8 la posizione che si occupa in seno alle istituzioni democratiche, tanto maggiore deve essere la sensibilit\u00e0 politica richiesta in casi come questo&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Scalzo risulta indagato nell&#8217;inchiesta &#8220;Erga omnes&#8221; condotta dalla Procura di Reggio Calabria su presunte irregolarit\u00e0 nella gestione dei fondi dei gruppi consiliari della Regione nella precedente legislatura. &#8220;Gi\u00e0 la scorsa settimana, dopo un confronto con la segreteria del Pd e in particolare con il vicesegretario nazionale Lorenzo Guerini, che ringrazio per l&#8217;attenzione che insieme al sottosegretario Luca Lotti ha rivolto alle vicende calabresi &#8211; afferma Scalzo -, avevo manifestato la mia piena disponibilit\u00e0 a ogni pi\u00f9 idonea iniziativa volta a superare il momento di impasse politica e istituzionale. All&#8217;ordine del giorno del prossimo Consiglio regionale ci saranno le mie dimissioni. <strong>Sulla mia vicenda personale, sono molto sereno perch\u00e9 le somme a me assegnate per l&#8217;attivit\u00e0 istituzionale del gruppo del Pd sono state puntualmente rendicontate nel rispetto della legge vigent<\/strong>e e del regolamento interno del gruppo del Pd.<\/p>\n<p>&nbsp;<\/p>\n<p>La magistratura bene ha fatto ad accendere i riflettori sull&#8217;utilizzo di queste risorse, su cui \u00e8 indispensabile un complessivo ripensamento e una radicale razionalizzazione. La discrezionalit\u00e0 a volte d\u00e0 luogo ad abusi inaccettabili ma sono certo che molte posizioni individuali, a cominciare dalla mia, saranno serenamente chiarite. Adesso \u00e8 tempo di mettersi a lavorare per il bene della Calabria dando continuit\u00e0 a un progetto politico che non riguarda solo la giunta regionale presieduta da Mario Oliverio ma anche il Consiglio, che nell&#8217;equilibrio delle funzioni interne alla Regione dovr\u00e0 continuare a esercitare nel migliore dei modi il proprio ruolo di garanzia, di controllo e di produzione legislativa&#8221;. &#8220;I<strong>l Consiglio regionale &#8211; conclude Scalzo &#8211; deve dare prova di rigore e seriet\u00e0. E credo che le mie dimissioni siano un atto che va in questa direzione&#8221;.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antonio Scalzo dopo vari tentennamenti e rifiuti ha finalmente deciso di abbandonare la propria poltrona.<\/p>\n","protected":false},"author":22,"featured_media":45356,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-45355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/45355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=45355"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/45355\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/45356"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=45355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=45355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=45355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}