{"id":45533,"date":"2015-07-14T15:04:32","date_gmt":"2015-07-14T13:04:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/mario-oliverio-domattina-protestera-contro-le-trivelle-nel-mar-ionio\/"},"modified":"2023-01-17T12:37:08","modified_gmt":"2023-01-17T11:37:08","slug":"44892-mario-oliverio-domattina-protestera-contro-le-trivelle-nel-mar-ionio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/44892-mario-oliverio-domattina-protestera-contro-le-trivelle-nel-mar-ionio\/","title":{"rendered":"Mario Oliverio, domattina, protester\u00e0 contro le &#8216;trivelle&#8217; nel mar Ionio"},"content":{"rendered":"<p><em><strong>Domani mattina i governatori di Basilicata, Puglia e Calabria, Marcello Pittella, Michele Emiliano e Mario Oliverio, parteciperanno a una manifestazione a Policoro (Matera) contro le &#8220;trivelle&#8221; nel mare Ionio.<\/strong><\/em> <!--more--><\/p>\n<p>Intanto, domani pomeriggio, durante il question time, il Ministro dell&#8217;Ambiente risponder\u00e0 a un&#8217;interrogazione presentata dall&#8217;on.<br \/>\nCosimo Latronico (Fi) &#8220;sul permesso di ricerca di idrocarburi localizzato nel golfo di Taranto, richiesto dalla societ\u00e0 Enel Longanesi&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domani mattina i governatori di Basilicata, Puglia e Calabria, Marcello Pittella, Michele Emiliano e Mario Oliverio, parteciperanno a una manifestazione a Policoro (Matera) contro le &#8220;trivelle&#8221; nel mare Ionio.<\/p>\n","protected":false},"author":20,"featured_media":45534,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-45533","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/45533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=45533"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/45533\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/45534"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=45533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=45533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=45533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}