{"id":4570,"date":"2012-09-28T14:43:36","date_gmt":"2012-09-28T12:43:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=4570"},"modified":"2023-01-17T13:37:52","modified_gmt":"2023-01-17T12:37:52","slug":"1546-recuperati-resti-2-soldati-grande-guerra","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/1546-recuperati-resti-2-soldati-grande-guerra\/","title":{"rendered":"Recuperati resti 2 soldati Grande Guerra"},"content":{"rendered":"<p>(ANSA) &#8211; TRENTO, 28 SET &#8211; I resti di due soldati della prima guerra mondiale sono stati recuperati dal ghiacciaio sotto Cima Presena, a circa 3.000 metri di quota. Quasi sicuramente &#8211; per gli esperti &#8211; i resti appartengono a soldati austro-ungarici, probabilmente artiglieri. Non avevano scarponi e uno dei due aveva ancora il cucchiaio infilato nelle<\/p>\n<p>  <!--more-->  <\/p>\n<p>fasce mollettiere. Sono stati trasportati con l&#8217;elicottero a Vermiglio da dove verranno trasferiti al Laboratorio di anatomia patologica dell&#8217;ospedale di Vicenza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(ANSA) &#8211; TRENTO, 28 SET &#8211; I resti di due soldati della prima guerra mondiale sono stati recuperati dal ghiacciaio sotto Cima Presena, a circa 3.000 metri di quota. Quasi sicuramente &#8211; per gli esperti &#8211; i resti appartengono a soldati austro-ungarici, probabilmente artiglieri. Non avevano scarponi e uno dei due aveva ancora il cucchiaio [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":4571,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16,5],"tags":[],"class_list":["post-4570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=4570"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4570\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/4571"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=4570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=4570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=4570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}