{"id":45775,"date":"2015-07-23T14:24:42","date_gmt":"2015-07-23T12:24:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/la-pizza-un-antica-tradizione-napoletana\/"},"modified":"2023-01-17T12:37:23","modified_gmt":"2023-01-17T11:37:23","slug":"45684-la-pizza-un-antica-tradizione-napoletana","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/45684-la-pizza-un-antica-tradizione-napoletana\/","title":{"rendered":"La pizza, un\u2019antica tradizione Napoletana"},"content":{"rendered":"<h4>Come prepararla al meglio.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>Oggi vorrei spiegarvi qualche trucchetto per realizzare la pizza come in pizzeria.\u00a0Partiamo da un p\u00f2 di storia. Si dice che la pizza per eccellenza sia quella napoletana, la famosa Pizza Margherita. Si narra che il pizzaiolo Raffaele Esposito che lavorava a Napoli nella pizzeria\u00a0\u201cPietro\u2026e Basta Cos\u00ec\u201d(1780) fu chiamato dal funzionario della reggia di Capodimonte che invit\u00f2 il pizzaiolo a realizzare una pizza in onore di Umberto I e sua moglie Margherita di Savoia. La regina grad\u00ec molto\u00a0la pizza che appunto prese il suo nome. Era una pizza molto semplice, ma sembrava la bandiera dell&#8217;Italia. Il verde del basilico, il bianco della mozzarella e il rosso del pomodoro.\u00a0Adesso vediamo come prepararla in casa.<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n<strong>Pizza Margherita<\/strong><br \/>\nTempo di cottura: 20 min<br \/>\n&nbsp;<br \/>\nINGREDIENTI PIZZA IN TEGLIA PER QUATTRO PERSONE<br \/>\n1,3 Kg Farina &#8220;00&#8221;<br \/>\n1 Litro Acqua<br \/>\n25 g. di Sale Fino<br \/>\n25 g. di Olio EVO<br \/>\n4 g. Lievito Secco<\/p>\n<p>&nbsp;<\/p>\n<p>PREPARAZIONE<br \/>\nImpastare la farina con l\u2019 80% di acqua e il lievito. Impastare per 10 minuti e aggiungere il sale, l\u2019olio evo e il restante dell\u2019acqua.\u00a0Quando l\u2019impasto \u00e8 pronto portare la pasta in un contenitore per alimenti e\u00a0mettere in frigo a 4\u00b0 per 24\/48 ore. Trascorso questo tempo passiamo allo staglio.\u00a0Prendere la pasta e fare dei panetti a freddo in base alla grandezza della teglia che utilizzate. Dopo aver fatto lo staglio mettete i panetti in un luogo non molto caldo potete anche lasciarli in cucina a far riposare per 6 ore.\u00a0Quando la pasta \u00e8 pronta per essere lavorata, la stendete e condite a vostro piacere.<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\nALTRI INGREDIENTI:<br \/>\n250 grammi di Mozzarella<br \/>\n200 grammi di pomodori pelati<br \/>\n&nbsp;<br \/>\nPREPARAZIONE:<br \/>\nPrendere il panetto lievitato e spianarlo su una teglia ben unta.\u00a0Condire con i pomodori pelati, olio, sale e basilico.\u00a0Cuocere per una ventina di minuti a 220 gradi.\u00a0Appena la pizza margherita sar\u00e0 quasi pronta, toglierla dal forno e condirla con la mozzarella\u00a0tagliata a cubetti e il basilico e infornate per altri 5 minuti.\u00a0Tagliare e servire ben calda.<\/p>\n<p>&nbsp;<\/p>\n<p>ABBINAMENTO:<\/p>\n<p>Di solito con la pizza si abbina la birra solo che si fa un piccolo errore poich\u00e9 la birra aiuta la fermentazione e essendoci nella pizza il lievito la cosa potrebbe creare qualche disturbo allo stomaco.\u00a0Noi consigliamo di abbinare un buon vino frizzante rosato per esempio , essendo un vino giovane e un p\u00f2 brioso servito fresco crea con la pizza un giusto abbinamento da provare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come prepararla al meglio.<\/p>\n","protected":false},"author":22,"featured_media":45776,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,34,124],"tags":[],"class_list":["post-45775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-magazine","category-ricette-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/45775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=45775"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/45775\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/45776"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=45775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=45775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=45775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}