{"id":45853,"date":"2015-07-26T06:43:19","date_gmt":"2015-07-26T04:43:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-44enne-in-manette-per-maltrattamenti-in-famiglia\/"},"modified":"2023-01-17T12:37:28","modified_gmt":"2023-01-17T11:37:28","slug":"45942-cosenza-44enne-in-manette-per-maltrattamenti-in-famiglia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/45942-cosenza-44enne-in-manette-per-maltrattamenti-in-famiglia\/","title":{"rendered":"Cosenza, 44enne in manette per maltrattamenti in famiglia"},"content":{"rendered":"<h4><strong>Non potr\u00e0 pi\u00f9 accedere nell&#8217;abitazione della moglie senza l&#8217;autorizzazione del giudice.<\/strong><\/h4>\n<p><!--more--><\/p>\n<p>COSENZA &#8211; La Squadra mobile di Cosenza ha eseguito un&#8217;ordinanza di applicazione di allontanamento dalla casa coniugale nei confronti di M.M.A., di 44 anni, accusato di maltrattamenti in famiglia, lesioni personali e minacce. L&#8217;uomo, secondo quanto dispone il provvedimento, non potr\u00e0 accedere nell&#8217;abitazione della moglie senza autorizzazione del giudice e non potr\u00e0 avvicinarsi ai luoghi frequentati dalla consorte. Secondo quanto accertato dalla Polizia, in pi\u00f9 occasioni, M.M.A. ha aggredito la moglie per gelosia sottoponendola a violenze psicologiche di varia natura, anche in presenza della figlia di sei anni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non potr\u00e0 pi\u00f9 accedere nell&#8217;abitazione della moglie senza l&#8217;autorizzazione del giudice.<\/p>\n","protected":false},"author":22,"featured_media":45854,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-45853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/45853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=45853"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/45853\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/45854"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=45853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=45853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=45853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}