{"id":45977,"date":"2015-07-29T13:49:56","date_gmt":"2015-07-29T11:49:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/morano-protesta-contro-la-riduzione-dei-collegamenti-con-castrovillari\/"},"modified":"2023-01-17T12:37:34","modified_gmt":"2023-01-17T11:37:34","slug":"46420-morano-protesta-contro-la-riduzione-dei-collegamenti-con-castrovillari","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/46420-morano-protesta-contro-la-riduzione-dei-collegamenti-con-castrovillari\/","title":{"rendered":"Morano protesta contro la riduzione dei collegamenti con Castrovillari"},"content":{"rendered":"<h4><strong>A seguito della riduzione delle corse di linea da Morano a Castrovillari e viceversa, il sindaco Nicol\u00f2 De Bartolo ha inviato una missiva di protesta ai vertici delle Ferrovie Calabro Lucane.<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>MORANO C. (CS) &#8211; In particolare il sindaco parla dei disagi che l\u2019iniziativa comporta per la popolazione, \u201cspecie quella anziana e non automunita\u201d, e chiede che siano tempestivamente ripristinati i collegamenti.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abDa anni \u2013 si legge nella nota scritta dal primo cittadino moranese alle Ferrovie della Calabria &#8211; la vostra azienda garantisce con puntualit\u00e0 e soddisfazione dell\u2019utenza i collegamenti nell\u2019area nord della Calabria. Tra i centri interessati, Morano Calabro \u00e8 certamente tra quelli che pi\u00f9 utilizzano e si avvalgono dei servizi di trasporto extraurbano, soprattutto per quanto riguarda i vettori da e per Castrovillari. Purtroppo recentemente sono pervenute alla nostra attenzione continue lamentele sfociate poi in ripetute e vibrate proteste presso la casa comunale, a causa della <strong>soppressione di numerose corse e del disagio che l\u2019iniziativa, unilaterale, ha provocato, soprattutto tra i cittadini anziani e nelle fasce pi\u00f9 deboli<\/strong>, che non hanno altro mezzo, n\u00e9 valide e praticabili alternative, per recarsi a Castrovillari, citt\u00e0 che ospita notoriamente servizi di primaria importanza, quali l\u2019ospedale, uffici fiscali, sedi di lavoro, ecc.<\/p>\n<p>&nbsp;<\/p>\n<p>Stante la particolare valenza sociale e la natura pubblica, che il trasporto extraurbano assume in un contesto come il nostro, ci sembra quanto mai inopportuno ridurre cos\u00ec drasticamente le interconnessioni tra centri che su di esse ripongono gran parte della programmazione quotidiana. Occorre pertanto porre rimedio a una situazione il cui perdurare acuirebbe le oggettive difficolt\u00e0 di cittadini deboli, <strong>ai quali verrebbe sottratto il diritto alla mobilit\u00e0 e penalizzato l\u2019accesso a un servizio pubblico essenziale<\/strong>. Chiediamo pertanto \u2013 conclude De Bartolo &#8211; che si ritorni sulle decisioni prese e si ripristino con somma urgenza le corse cancellate\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A seguito della riduzione delle corse di linea da Morano a Castrovillari e viceversa, il sindaco Nicol\u00f2 De Bartolo ha inviato una missiva di protesta ai vertici delle Ferrovie Calabro Lucane.<\/p>\n","protected":false},"author":22,"featured_media":45978,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-45977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/45977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=45977"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/45977\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/45978"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=45977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=45977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=45977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}