{"id":45994,"date":"2015-07-30T08:13:40","date_gmt":"2015-07-30T06:13:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/investe-un-conoscente-con-il-suv-e-lo-uccide-con-unascia-omicida-confessa-mi-vessava-da-anni\/"},"modified":"2023-01-17T12:37:35","modified_gmt":"2023-01-17T11:37:35","slug":"46471-investe-un-conoscente-con-il-suv-e-lo-uccide-con-unascia-omicida-confessa-mi-vessava-da-anni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/46471-investe-un-conoscente-con-il-suv-e-lo-uccide-con-unascia-omicida-confessa-mi-vessava-da-anni\/","title":{"rendered":"Investe un &#8216;conoscente&#8217; con il Suv e lo uccide con un&#8217;ascia, omicida confessa: &#8216;Mi vessava da anni&#8217;"},"content":{"rendered":"<h4>La cruenta aggressione si \u00e8 consumata\u00a0domenica scorsa sulla statale 106.<\/h4>\n<p><!--more--><br \/>\nPALIZZI (RC)\u00a0&#8211; Si \u00e8 tenuto ieri l&#8217;interrogatorio di garanzia di Francesco Ferraro, il commerciante di 41 anni arrestato dai Carabinieri per l&#8217;omicidio del 51enne Antonio Genova, ucciso la scorsa domenica sera a Palizzi Marina a colpi d&#8217;ascia. L&#8217;arrestato, che si era consegnato ai Carabinieri nelle fasi successive all&#8217;omicidio, ha confermato davanti al gip presso il Tribunale di Locri, Sergio Malgeri, la confessione gi\u00e0 resa agli investigatori. Ai Carabinieri Ferraro ha raccontato che Genova lo vessava da pi\u00f9 di 20 anni, e che ha commesso il delitto perche&#8217; esasperato da tali vessazioni relative a questioni private.\u00a0All\u2019omicidio hanno assistito diversi testimoni. Di recente Genova aveva squarciato gli pneumatici della vettura di propriet\u00e0 di Ferraro e del vicino di casa. Un mese fa invece pare avesse dato fuoco all&#8217;auto del padre. La vittima nel 2008 fu arrestata nel centro del piccolo comune di Palizzi perch\u00e8 con un revolver con matricola abrasa minacciava una donna, la compagna di suo zio, aveva sparato sette colpi in aria terrorizzando i figli della signora aggredita. Genova era noto alle forze dell&#8217;ordine per essere stato arrestato a Milano per omicidio.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\">In foto il ritrovamento del corpo di\u00a0Genova<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cruenta aggressione si \u00e8 consumata\u00a0domenica scorsa sulla statale 106.<\/p>\n","protected":false},"author":22,"featured_media":45995,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-45994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/45994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=45994"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/45994\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/45995"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=45994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=45994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=45994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}