{"id":46175,"date":"2015-08-04T10:43:13","date_gmt":"2015-08-04T08:43:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/inizia-domani-lestate-nei-quartieri-a-cosenza-una-settimana-di-musica-ed-intrattenimento-programma\/"},"modified":"2023-01-17T12:37:46","modified_gmt":"2023-01-17T11:37:46","slug":"47084-inizia-domani-lestate-nei-quartieri-a-cosenza-una-settimana-di-musica-ed-intrattenimento-programma","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/47084-inizia-domani-lestate-nei-quartieri-a-cosenza-una-settimana-di-musica-ed-intrattenimento-programma\/","title":{"rendered":"Inizia domani l&#8217;Estate nei Quartieri, a Cosenza una settimana di musica ed intrattenimento (PROGRAMMA)"},"content":{"rendered":"<h4>Il Comune di Cosenza ripropone l&#8217;iniziativa\u00a0che intrattiene &#8216;a domicilio&#8217; i cittadini che trascorrono in citt\u00e0 il mese di Agosto.<\/h4>\n<h4><!--more--><\/h4>\n<p>COSENZA &#8211; \u201cL&#8217;Estate nei quartieri \u00e8 un appuntamento irrinunciabile \u2013 commenta l\u2019Assessore Succurro &#8211; un&#8217;iniziativa che riscuote successo e che i quartieri della nostra citt\u00e0 attendono, non appena si ferma l&#8217;intrattenimento sul Lungofiume. Il grande caldo di questa stagione estiva invoglia ulteriormente a trascorrere parte della serata all&#8217;aperto e, soprattutto, in grande spensieratezza\u201d.\u00a0Si comincia <strong>Mercoled\u00ec 5 Agosto da Donnici Superiore<\/strong>\u00a0alle 22.00 per una serata all&#8217;insegna dei &#8220;Ricordi pi\u00f9 belli&#8221;. Ce li propone Paquale Parise con il suo spettacolo evergreen, fatto di balli caraibici, di liscio, di musica anni 60. Tutti in pista, nessuno escluso.\u00a0<strong>Gioved\u00ec 6 Agosto piazza Loreto<\/strong>\u00a0a partire dalle 22.00 vedr\u00e0 il ritorno della Rassegna Itinerante del Folklore Internazionale, promossa da due Associazioni: \u201cCalabria Citra\u201d di Morano Calabro e \u201cI Cantori del Pettoruto\u201d di San Sosti.\u00a0Quest&#8217;anno l&#8217;incontro \u00e8 fra le tradizioni del folklore italiano &#8211; presente con due gruppi, uno calabrese ed uno veneto &#8211; e quelle di gruppi stranieri provenienti da Polonia, Slovacchia ed India. La manifestazione sar\u00e0 l&#8217;atto conclusivo di una variegata sfilata che partir\u00e0 alle 21 da piazza dei Bruzi e percorrer\u00e0 quindi tutto il centro per arrivare poi in piazza per l&#8217;esibizione finale.\u00a0L\u2019Estate nei quartieri prosegue nei giorni successivi toccando <strong>Borgo Partenope il 7 Agosto<\/strong> con Luca Andrieri, <strong>via degli Stadi l&#8217;8 Agosto<\/strong> con Fausto Guido Trio <strong>e Sant&#8217;Ippolito il 12 Agosto<\/strong> con lo spettacolo Iennu Brigannu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di Cosenza ripropone l&#8217;iniziativa\u00a0che intrattiene &#8216;a domicilio&#8217; i cittadini che trascorrono in citt\u00e0 il mese di Agosto.<\/p>\n","protected":false},"author":22,"featured_media":46176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[41,34],"tags":[],"class_list":["post-46175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intrattenimento","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/46175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=46175"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/46175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/46176"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=46175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=46175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=46175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}