{"id":46214,"date":"2015-08-05T11:11:48","date_gmt":"2015-08-05T09:11:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cras-liberate-a-rende-due-poiane-e-un-gheppio-occhiuto-annuncia-iniziative-con-i-giovani\/"},"modified":"2023-01-17T12:37:48","modified_gmt":"2023-01-17T11:37:48","slug":"47248-cras-liberate-a-rende-due-poiane-e-un-gheppio-occhiuto-annuncia-iniziative-con-i-giovani","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/47248-cras-liberate-a-rende-due-poiane-e-un-gheppio-occhiuto-annuncia-iniziative-con-i-giovani\/","title":{"rendered":"Cras, liberate a Rende due poiane e un gheppio. Occhiuto annuncia iniziative con i giovani"},"content":{"rendered":"<h4><strong>Il Cras di Rende ha liberato due poiane e un gheppio che tornano in libert\u00e0 nella campagna di Rende.<\/strong><\/h4>\n<p><!--more--><\/p>\n<p>RENDE (CS) &#8211; L&#8217;attivit\u00e0 del Cipr (Comitato italiano per la protezione degli uccelli rapaci), ancora una volta emoziona e fa crescere il senso di rispetto per la natura e le specie che questa accoglie. Ieri anche la Provincia di Cosenza, che contribuisce in maniera assidua alle attivit\u00e0 del Cras di Rende, il Centro Recupero Animali selvatici, ha partecipato alla liberazione dei tre esemplari. Protagonista della liberazione proprio il presidente Mario Occhiuto che ha rilasciato una delle due poiane. All\u2019iniziativa ha partecipato la Polizia Provinciale, impegnata attivamente per la tutela della fauna selvatica. Tra i presenti anche il commissario Antonella Pignataro, l\u2019assistente Capo Luigi Perna e l\u2019agente Marcella De Lutio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-large wp-image-47251 aligncenter\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/08\/cipr3-534x400.jpg\" alt=\"cipr3\" width=\"534\" height=\"400\" title=\"\"><\/p>\n<p>La collaborazione proficua tra Cipr e Polizia Provinciale, che continua da molti anni, ha avuto l\u2019obiettivo comune di tutelare sempre pi\u00f9 e meglio la fauna selvatica della nostra regione. In particolare, la Polizia provinciale nel corso del 2014 ha tratto in salvo 203 uccelli appartenenti a specie protette, e 105 nel 2015 per un totale dio 308 uccelli feriti, recuperati e affidate alle cure dei veterinari.<strong> Il Cras di Rende<\/strong>, \u00e8 una struttura in grado di accogliere un numero considerevole di animali cui garantire l\u2019assistenza, i volontari, Nicoletta Boldrini, Antonio Iantorno e Daria Stepancicih, sono altamente specializzati, con competenze specifiche nel campo delle scienze naturali e alcuni di loro si occupano di fauna selvatica da oltre un ventennio, con una solida esperienza costruita sul campo. In settimana, inoltre, i responsabili del Cras provvederanno a rimettere in libert\u00e0 anche 4 assioli e 10 civette. E\u2019 stata l\u2019occasione per il Presidente della Provincia Occhiuto di conoscere una realt\u00e0 importante come il Cras di Rende.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-large wp-image-47252 aligncenter\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/08\/cipr5-534x400.jpg\" alt=\"cipr5\" width=\"534\" height=\"400\" title=\"\"><\/p>\n<p>Il presidente ha avuto parole di elogio per le attivit\u00e0 che si svolgono presso la \u201c<strong>Casa della Natura<\/strong>\u201d ed ha lodato, in modo particolare, le attivit\u00e0 di Educazione Ambientale ed i lavori che sono stati realizzati dagli alunni delle scuole che hanno partecipato alle attivit\u00e0 di Educazione Ambientale del Cipr a Casa della Natura. Infine il Presidente ha rassicurato i responsabili del Cipr che si prodigher\u00e0 affinch\u00e8 alla struttura non venga meno l\u2019aiuto finanziario per garantire la cura e la riabilitazione dei selvatici, ed anche lo scopo di far crescere, soprattutto nei giovanissimi, una sensibilit\u00e0 e un senso di responsabilit\u00e0 sempre maggiori verso la natura e la tutela dell\u2019ambiente. In particolare il presidente Occhiuto ha pensato ad un coinvolgimento attivo con la &#8220;Citt\u00e0 dei ragazzi&#8221; di Cosenza per organizzare visite guidate nella struttura dove i bambini potranno ammirare da vicino gli uccelli, conoscere le diverse specie e le loro caratteristiche e partecipare a laboratori didattici sulla tutela dell\u2019ambiente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Cras di Rende ha liberato due poiane e un gheppio che tornano in libert\u00e0 nella campagna di Rende.<\/p>\n","protected":false},"author":22,"featured_media":46215,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,44],"tags":[],"class_list":["post-46214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/46214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=46214"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/46214\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/46215"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=46214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=46214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=46214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}