{"id":46239,"date":"2015-08-06T10:05:17","date_gmt":"2015-08-06T08:05:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tragedia-nel-cosentino-giovane-si-impicca-con-i-genitori-in-casa\/"},"modified":"2023-01-17T12:37:50","modified_gmt":"2023-01-17T11:37:50","slug":"47335-tragedia-nel-cosentino-giovane-si-impicca-con-i-genitori-in-casa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/47335-tragedia-nel-cosentino-giovane-si-impicca-con-i-genitori-in-casa\/","title":{"rendered":"Tragedia nel cosentino giovane si impicca in soffitta mentre i genitori sono in casa"},"content":{"rendered":"<h4>Le urla del signor Cesare\u00a0riecheggiano ancora tra i vicoli di via Polmo.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>NOCARA (CS) &#8211; Sua moglie non riesce ancora a dimenticare quel grido cupo, macabro indizio di un triste presagio. La\u00a0famiglia Violante \u00e8 distrutta all&#8217;alba dei funerali del figlio 32enne tenutisi ieri pomeriggio nella chiesa di San Nicola di Bari a Nocara. Un ragazzo educato, senza troppi grilli per la testa che viveva tranquillo con i suoi familiari. Non si vedeva mai al bar a bere o vagabondare per il paese. Cos\u00ec lo descrivono i suoi vicini di casa che si stringono nel dolore dei genitori del ragazzo che ha deciso di porre fine alla propria esistenza in un caldo pomeriggio d&#8217;Agosto. Da pi\u00f9 di tre\u00a0anni la relazione sentimentale con una giovane del posto che frequentava da diverso tempo era terminata, ma i due pare fossero ancora in ottimi rapporti. <strong>Era in cerca di lavoro da qualche mese dopo che il contratto con una ditta che si occupa del rimboschimento della zona era scaduto. <\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Sua madre (in vita, nonostante una nota testata abbia affermato che sia deceduta) affranta racconta che Marted\u00ec dopo aver pranzato era andato in mansarda. Senza dire nulla: nessun segno di malessere o insofferenza. Decide di fare un cappio con un nodo. Il giogo di morte al collo. Pochi minuti di stenti, poi la morte. <strong>A ritrovare il corpo di Giuseppe penzoloni nel sottotetto il padre che, non sentendo alcun rumore, era andato a controllare cosa stesse facendo. Un&#8217;immagine sconvolgente a cui l&#8217;uomo ha reagito con urla di disperazione.<\/strong> Al piano sottostante la madre ancora ad oggi incredula di quanto possa essere accaduto. Entrambi erano in casa e non si sono resi conto di nulla. Un cruccio a cui non riescono a rassegnarsi. Pare che non fosse la prima volta che il 32enne tentava l&#8217;estremo gesto. In due occasioni, riferiscono i vicini di casa, avrebbe provato a suicidarsi. Una volta tagliandosi le vene, un&#8217;altra volta a Roma cercando di lanciarsi sotto un treno. Una situazione emotiva forse precaria di un giovane che senza alcun motivo apparente ha gettato nello sgomento un&#8217;intera comunit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\">In foto il quartiere in cui Giuseppe viveva con i genitori<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le urla del signor Cesare\u00a0riecheggiano ancora tra i vicoli di via Polmo.<\/p>\n","protected":false},"author":18,"featured_media":46240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-46239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/46239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=46239"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/46239\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/46240"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=46239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=46239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=46239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}