{"id":46265,"date":"2015-08-07T08:47:43","date_gmt":"2015-08-07T06:47:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/sequestrate-boe-posizionate-illecitamente-nelle-aree-destinate-ai-bagnanti\/"},"modified":"2023-01-17T12:37:51","modified_gmt":"2023-01-17T11:37:51","slug":"47442-sequestrate-boe-posizionate-illecitamente-nelle-aree-destinate-ai-bagnanti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/47442-sequestrate-boe-posizionate-illecitamente-nelle-aree-destinate-ai-bagnanti\/","title":{"rendered":"Sequestrate boe posizionate illecitamente nelle aree destinate ai bagnanti"},"content":{"rendered":"<h4>I gavitelli abusivi sono stati prelevati dalla guardia costiera e depositati nei magazzini in attesa che vengano regolarmente smaltiti.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA\u00a0&#8211; Nei mesi di giugno e luglio la Capitaneria di porto di Reggio Calabria, ha condotto, lungo l&#8217;intero territorio di Reggio Calabria e Villa San Giovanni, un&#8217;intensa attivit\u00e0 di repressione e contrasto all&#8217;annoso e diffusissimo fenomeno dei gavitelli abusivamente posizionati lungo l&#8217;intero litorale. La collocazione delle boe d&#8217;ormeggio lungo la fascia costiera in assenza del previsto titolo di concessione demaniale, spesso a pochi metri dalla battigia, <strong>oltre a deturpare l&#8217;ambiente marino, rappresenta un comportamento penalmente rilevante, oltreche&#8217; un vero pericolo per la sicurezza della navigazione per l&#8217;assenza di idonee segnalazioni. Inoltre, impediscono, al contempo, la libera e sicura fruizione da parte dei bagnanti,<\/strong> atteso che le imbarcazioni potenzialmente utilizzatrici di tali ormeggi transitano all&#8217;interno della fascia di mare riservata alla balneazione.<\/p>\n<p>&nbsp;<\/p>\n<p>Si \u00e8 proceduto al salpamento delle boe che sono state poste sotto sequestro penale cautelare, poi convalidato dall&#8217;autorit\u00e0 giudiziaria, e depositate presso i locali della Capitaneria di porto in attesa del successivo smaltimento. In taluni casi, ed in particolare in localit\u00e0 Pellaro e a Porticello, oltre a accertare la presenza dei gavitelli singolarmente disposti lungo il litorale, si \u00e8 verificato che, grazie al loro particolare posizionamento, <strong>gli stessi rappresentavano un vero e proprio &#8220;campo boe&#8221;, gestito da soggetti i quali, gi\u00e0 titolari di regolare licenza concessoria avevano pero&#8217; illecitamente aumentato in modo considerevole lo spazio acqueo occupato.<\/strong> Gli stessi sono stati prontamente deferiti all&#8217;autorita&#8217; giudiziaria e diffidati alla rimozione delle imbarcazioni ormeggiate e delle relative boe d&#8217;ormeggio. Tale operazione, che ha portato al sequestro di circa 150 gavitelli, continuera&#8217; anche nelle prossime settimane a tutela sia del patrimonio ambientale che a tutela dell&#8217;Erario, rappresentando il posizionamento delle boe in assenza di regolare concessione un danno erariale per il mancato incameramento dei canoni demaniali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I gavitelli abusivi sono stati prelevati dalla guardia costiera e depositati nei magazzini in attesa che vengano regolarmente smaltiti.<\/p>\n","protected":false},"author":22,"featured_media":46266,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-46265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/46265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=46265"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/46265\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/46266"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=46265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=46265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=46265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}