{"id":46348,"date":"2015-08-10T08:24:55","date_gmt":"2015-08-10T06:24:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/coppa-italia-primo-match-in-trasferta-per-i-lupi-per-il-cosenza-e-sconfitta\/"},"modified":"2023-01-17T12:37:58","modified_gmt":"2023-01-17T11:37:58","slug":"47692-coppa-italia-primo-match-in-trasferta-per-i-lupi-per-il-cosenza-e-sconfitta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/47692-coppa-italia-primo-match-in-trasferta-per-i-lupi-per-il-cosenza-e-sconfitta\/","title":{"rendered":"Coppa Italia TIM: un ottimo Cosenza a Vicenza, sconfitto solo ai calci di rigore"},"content":{"rendered":"<h4>La compagine rossoblu\u00a0ha stretto in una morsa difensiva il Vicenza portandolo ai calci di rigore dopo l&#8217;1 a 1 dei tempi supplementari. Ancora in rete Arrighini<!--more--><\/h4>\n<h4><\/h4>\n<p>VICENZA &#8211; Decisive le parate di Marcone sui tiri di Arrigoni e Ciancio. Resta la buona prestazione della squadra di Roselli che sfiora il gol durante i tempi regolamentari con una traversa piena di La Mantia nel corso del secondo tempo. Ai supplementari calcio a giro di interno destro di Arrgihini con il pallone che si infila sotto l\u2019incrocio. Corsi \u00a0tocca il pallone con la mano proprio all\u2019ultimo giro di lancetta del primo tempo supplementare. Scattano cartellino giallo ed espulsione, \u00e8 quindi Giacomelli che firma il pari dopo che Perina aveva intercettato il tiro. Si chiude positivamente la partecipazione, inattesa (rossoblu \u201cripescati\u201d dopo la mancata iscrizione di alcune squadre nella Lega Pro), alla Lega Pro: il successo di Ascoli e la sfida di Vicenza conclusa sul 5 &#8211; 3. \u00a0La consapevolezza che Meluso ha messo nelle mani di Roselli una buona squadra, in attesa che Arrighini possa essere utilizzato a tempo pieno. L\u2019ex attaccante del Pisa ha gi\u00e0 regalato due goal, pur essendo entrato a partita in corso in entrambe le occasioni. L\u2019infiammazione al tendine di un ginocchio lo limita. Raimondi l\u2019ultimo arrivato ha dimostrato la propria professionalit\u00e0 e competenza. Nel nuovo campionato appaiono ora concreti i presupposti per vivere la Lega Pro da protagonisti.<\/p>\n<p><strong>Vicenza-Cosenza<\/strong>: 5-3 (d.c.r)<br \/>\n<strong>Marcatori<\/strong>: 1\u2019 p.t.s. Arrighini (C), 15\u2019 p.t.s.\u00a0Giacomelli (V) su rigore.<\/p>\n<p>Sequenza rigori dopo i tempi supplementari: Arrighini (C) gol, Giacomelli (V) gol, Caccetta (C) gol, Vita (V) gol, Arrigoni (C) parato, Urso (V) gol, Ciancio (C) parato, Mantovani (V) gol.<\/p>\n<p><strong>Vicenza (4-3-3<\/strong>): Marcone, Sampirisi (dal 37\u2019 s.t. Camisa), Brighenti, Mantovani, D\u2019Elia, Gagliardini, Pazienza (dal 25\u2019 s.t. Urso), Sbrissa; Vita, Gatto (dal 26\u2019 s.t. Raicevic), Giacomelli.<br \/>\n<strong>A disposizione<\/strong>: Vigorito, Pinato, Magri, Corticchia, Spiridonovic, Modic, Cecconello, Gora, Kerezovic.<br \/>\n<strong>Allenatore<\/strong>: Pasquale Marino<\/p>\n<p><strong>Cosenza Calcio (4-4-2)<\/strong>: Perina, Ciancio, Tedeschi, Blondett, Pinna, Corsi, Caccetta,\u00a0 Arrigoni, Criaco (dal 18\u2019 s.t. Guerriera), Vutov (dal 18\u2019 s.t. Arrighini), La Mantia (dal 33\u2019 s.t. Raimondi).<br \/>\n<strong>A disposizione<\/strong>: Saracco, Soprano, Di Somma, Novello, Fiordilino, Ventre.<br \/>\nAllenatore: Giorgio Roselli<\/p>\n<p>Arbitro: Riccardo Ros della sezione di Pordenone, assistenti Alessio Tolfo della sezione di Pordenone, Giovanni Baccini della sezione di Conegliano, quarto ufficiale Luigi Rossi della sezione di Rovigo.<\/p>\n<p><strong>Note<\/strong>: ammoniti Pazienza (V), Giacomelli (V), Raimondi (C). Espulso al 15\u2019 p.t.s. Corsi (C) per somma di ammonizioni.<\/p>\n<p>Recupero: 1\u2019 p.t.; 4\u2019 s.t.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La compagine rossoblu\u00a0ha stretto in una morsa difensiva il Vicenza portandolo ai calci di rigore dopo l&#8217;1 a 1 dei tempi supplementari. Ancora in rete Arrighini<\/p>\n","protected":false},"author":24,"featured_media":46349,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-46348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/46348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=46348"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/46348\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/46349"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=46348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=46348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=46348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}