{"id":46440,"date":"2015-08-12T15:26:34","date_gmt":"2015-08-12T13:26:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/alluvione-a-rossano-e-corigliano-legambiente-rischi-e-danni-grazie-alla-gestione-irresponsabile-del-territorio\/"},"modified":"2023-01-17T12:38:03","modified_gmt":"2023-01-17T11:38:03","slug":"47984-alluvione-a-rossano-e-corigliano-legambiente-rischi-e-danni-grazie-alla-gestione-irresponsabile-del-territorio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/47984-alluvione-a-rossano-e-corigliano-legambiente-rischi-e-danni-grazie-alla-gestione-irresponsabile-del-territorio\/","title":{"rendered":"Alluvione a Rossano e Corigliano, Legambiente: &#8220;Rischi e danni grazie alla gestione irresponsabile del territorio&#8221;"},"content":{"rendered":"<h4><strong>\u201cBasta lacrime di coccodrillo. Rischi e danni continueranno grazie alla gestione irresponsabile del territorio\u201d.<\/strong><\/h4>\n<p><!--more--><br \/>\nROSSANO (CS) &#8211; L\u2019evento di oggi in Calabria, dove permane un\u2019allerta meteo per altre 24 ore, dimostra tutta la fragilit\u00e0 di una regione con l\u201989% dei Comuni a forte rischio idrogeologico, dove il consumo e l\u2019impermeabilizzazione del suolo non conoscono freno. E Legambiente dice &#8216;basta alle lacrime di Coccodrillo&#8217;. Dal 2000 al 2015 in Italia si sono verificati oltre 2 mila eventi atmosferici estremi con frane e allagamenti che hanno causato la morte di pi\u00f9 di 300 persone e richiesto uno stanziamento economico di quasi un miliardo di euro l\u2019anno solo negli ultimi cinque anni.<\/p>\n<p>Il rischio quindi non riguarda solo la Calabria: sono ben 6.633 i Comuni italiani in cui sono presenti aree a rischio idrogeologico e oltre 6 milioni di cittadini si trovano ogni giorno in zone esposte al pericolo di frane o alluvioni, a causa della forte urbanizzazione che ha interessato anche le aree a maggior rischio, e se \u00e8 ormai condivisa l\u2019urgenza della messa in sicurezza del territorio, \u00e8 del tutto evidente che larga parte dei progetti che vengono portati avanti sono inadeguati rispetto alle nuove sfide che i cambiamenti climatici ci pongono con sempre maggiore urgenza. C\u2019\u00e8 bisogno di approcci diversi e di strategie di adattamento capaci di ripensare le politiche infrastrutturali, nella direzione delle nuove politiche comunitarie dei piani clima delle citt\u00e0 europee.<\/p>\n<p>\u201cIl governo ha iniziato a fare qualcosa sul rischio idrogeologico, ma si rischia di finanziare progetti inadatti e vecchi \u2013 ha dichiarato il presidente di Legambiente Vittorio Cogliati Dezza -. Dei 650 milioni di euro recentemente sbloccati per il rischio, per esempio, nulla andr\u00e0 alle regioni del Sud.<\/p>\n<p>Ma i cambiamenti climatici, con effetti sempre pi\u00f9 forti e frequenti, ci obbligano a guardare in modo diverso al territorio, perch\u00e9 proprio la gestione sciagurata del territorio pu\u00f2 contribuire ad aggravare i rischi per le persone e le cose. <strong>Non c\u2019\u00e8 pi\u00f9 tempo e non possono esserci ulteriori scuse.<\/strong> Occorre investire \u2013 subito \u2013 su pianificazione e manutenzione del territorio, sulla delocalizzazione degli edifici a rischio, sulle politiche di adattamento al clima con progetti realmente efficaci e mirati per ogni territorio\u201d.<\/p>\n<p>\u201cVogliamo esprimere solidariet\u00e0 e vicinanza ai concittadini di Rossano e Corigliano, delle zone del catanzarese e del reggino, e alle istituzioni in questa fase delicata di emergenza e soccorso \u2013 ha aggiunto il presidente di Legambiente Calabria Francesco Falcone -. La Regione dichiari lo stato di emergenza e metta mano al piano di difesa del suolo e allo stop al consumo di suolo. Solo fermando la cementificazione selvaggia, l\u2019aggressione ai fiumi e ai boschi sar\u00e0 possibile diminuire i rischi degli effetti climatici estremi, oggi sempre pi\u00f9 frequenti\u201d.<\/p>\n<p>\u201cIl Governo italiano non ha ancora una politica per affrontare il rischio climatico \u2013 ha concluso Vittorio Cogliati Dezza \u2013 e se ha approvato (in ritardo) un documento di obiettivi generali con la strategia di adattamento al clima, ancora nulla si sta muovendo per arrivare all&#8217;approvazione del piano nazionale, ossia lo strumento che dovrebbe finalmente permettere di passare dagli obiettivi generali agli interventi concreti utilizzando anche la spesa dei fondi europei a disposizione delle Regioni che, ricordiamolo, nella programmazione 2014-2020 sono rilevanti per questo tipo di interventi, ma che rischiano, in assenza di chiari obiettivi e di una attenta regia di rimanere inutilizzati\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cBasta lacrime di coccodrillo. Rischi e danni continueranno grazie alla gestione irresponsabile del territorio\u201d.<\/p>\n","protected":false},"author":22,"featured_media":46441,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-46440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/46440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=46440"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/46440\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/46441"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=46440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=46440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=46440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}