{"id":46539,"date":"2015-08-17T08:00:24","date_gmt":"2015-08-17T06:00:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/presentati-i-primi-appuntamenti-del-settembre-rendese-2015-questanno-compie-mezzo-secolo\/"},"modified":"2023-01-17T12:38:08","modified_gmt":"2023-01-17T11:38:08","slug":"48261-presentati-i-primi-appuntamenti-del-settembre-rendese-2015-questanno-compie-mezzo-secolo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/48261-presentati-i-primi-appuntamenti-del-settembre-rendese-2015-questanno-compie-mezzo-secolo\/","title":{"rendered":"Presentati i primi appuntamenti del &#8216;Settembre Rendese 2015&#8217;. Quest&#8217;anno compie mezzo secolo"},"content":{"rendered":"<h4><strong>Il calendario del Settembre Rendese 2015 \u00e8 pronto e quest&#8217;anno l&#8217;evento \u00e8 ancora pi\u00f9 importante perch\u00e9 si festeggia il 50esimo anno della manifestazione.<\/strong><\/h4>\n<p><!--more--><\/p>\n<p>RENDE (CS) &#8211; Il Settembre Rendese compie 50 anni e quest\u2019anno, l\u2019Amministrazione Manna e l&#8217;assessore alla Cultura e agli Eventi Vittorio Toscano, hanno preparato un cartellone degno di questo nome: \u00a0\u201cE\u2019 stato difficile far quadrare i conti, ma siamo pronti\u201d\u00a0&#8211; ha dichiarato l&#8217;assessore\u00a0Toscano nel sottolineare\u00a0ancora una volta, la natura di questo Settembre Rendese che come lo scorso anno mira \u201ca valorizzare e a metter in vetrina le capacit\u00e0 organizzative, artistiche e umane del nostro territorio, ma quest\u2019anno c\u2019\u00e8 anche qualche sorpresa in pi\u00f9 grazie anche al contributo degli sponsor privati che per questa edizione storica non si sono fatti pregare pi\u00f9 di tanto a scendere in campo. E li ringrazio fin da oggi\u201d.\u00a0<span style=\"line-height: 1.5;\">Ed ecco i primi nomi dei<\/span><span style=\"line-height: 1.5;\">\u00a0protagonisti che animeranno le serate al ritorno delle meritate vacanze: Manlio Dov\u00ec, Francesco Paolantoni e Giuliana De Sio<\/span><span style=\"line-height: 1.5;\">, Anna Tatangelo&#8230;<\/span><\/p>\n<p>Il sindaco di Rende Marcello Manna ha detto fin dall\u2019inizio del suo insediamento che \u201csar\u00e0 pi\u00f9 difficile riportare la gente al centro storico che uscire dal predissesto\u201d, ma questo Settembre Rendese \u00e8 l\u2019occasione giusta per concretizzare quella spinta preparata a tavolino in questo primo anno di legislatura. Partiranno progetti importanti, ma gli eventi dice il sindaco Manna: \u201cdevono e possono aiutare ancora di pi\u00f9 questo nostro processo di avvicinamento a rendere il Borgo Antico di nuovo abitabile e vivibile nella quotidianit\u00e0\u201d e anche per questo motivo l\u2019assessore Toscano nel cartellone ha dato centralit\u00e0 ad una &#8216;Rende Paese&#8217; che ha tanta voglia di ritornare animata e viva come ai bei tempi.\u00a0<span style=\"line-height: 1.5;\">Il\u00a0<\/span><span style=\"line-height: 1.5;\">teatro all\u2019aperto si concentrer\u00e0 soprattutto nel borgo antico; la musica d\u2019autore e i concerti avranno come location la piazza del Museo del Presente.\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><strong>Ecco il programma con i primi appuntamenti del Settembre Rendese 2015<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-48263 aligncenter\" src=\"http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/08\/settembre-Rendese-305x400.jpg\" alt=\"settembre Rendese\" width=\"429\" height=\"618\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il calendario del Settembre Rendese 2015 \u00e8 pronto e quest&#8217;anno l&#8217;evento \u00e8 ancora pi\u00f9 importante perch\u00e9 si festeggia il 50esimo anno della manifestazione.<\/p>\n","protected":false},"author":19,"featured_media":46540,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,44],"tags":[],"class_list":["post-46539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/46539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=46539"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/46539\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/46540"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=46539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=46539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=46539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}