{"id":46892,"date":"2015-08-31T10:54:49","date_gmt":"2015-08-31T08:54:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/alluvione-falcone-di-legambiente-incuria-del-territorio-determinata-anche-dal-clientelismo\/"},"modified":"2023-01-17T12:38:31","modified_gmt":"2023-01-17T11:38:31","slug":"49453-alluvione-falcone-di-legambiente-incuria-del-territorio-determinata-anche-dal-clientelismo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/49453-alluvione-falcone-di-legambiente-incuria-del-territorio-determinata-anche-dal-clientelismo\/","title":{"rendered":"Alluvione, Falcone di Legambiente: &#8220;incuria del territorio determinata anche dal clientelismo&#8221; (AUDIO INTERVISTA)"},"content":{"rendered":"<h4><strong>La Calabria ha bisogno di verit\u00e0 sui disastri naturali che la colpiscono, perch\u00e8 aldil\u00e0 dell&#8217;evento atmosferico straordinario, esiste una precisa responsabilit\u00e0 sull&#8217;incuria e la gestione del suolo e del territorio.<\/strong><\/h4>\n<p><!--more--><\/p>\n<p>COSENZA &#8211; Dopo l\u2019alluvione che ha devastato Rossano, in Calabria, \u00e8 stato celere l\u2019arrivo del ministro dell\u2019Ambiente Gian Luca Galletti, ma c&#8217;\u00e8 chi ha sperato che il suo arrivo non sia stato solo un modo per constatare la gravit\u00e0 dei danni a nubifragio terminato perch\u00e8 questo non basta.\u00a0In questa direzione era intervenuta Legambiente e il presidente Francesco Falcone, all&#8217;epoca della visita del Ministro aveva detto: \u00abGalletti ci aiuti a capire se il disastro \u00e8 avvenuto per cause naturali oppure \u00e8 la mano dell\u2019uomo ad averlo provocato. Se c\u2019\u00e8 attinenza tra quanto successo e la mancata manutenzione dei fiumi e dei torrenti (come il Citrea), se le costruzioni abusive presenti nel territorio e la cementificazione di aree prima a verde pubblico, a destinazione agricola o non si siano poi trasformate in aree di espansione edilizia con l\u2019approvazione dei piani urbanistici comunali per obbedire alle lobby clientelari e delle macchine del voto del cemento aggravando una situazione gi\u00e0 complicata dall\u2019orografia del territorio. Ci aiuti a capire, signor Ministro, se sia fondata la denuncia fatta nel 2013 sul torrente Coriglianeto e Leccalardo a Corigliano e se si sia costruito o meno abusivamente ed illegalmente in una zona classificata ad alto rischio idrogeologico e se nell\u2019alveo del fiume Crati ancora insistono illegalmente agrumeti\u00bb. Legambiente inoltre, aveva chiesto al ministro Galletti di chiedere, a sua volta alla Regione Calabria, una legge per bloccare il consumo di suolo e per la tutela del paesaggio costiero, convinca i governanti calabresi che questa \u00e8 la strada da seguire. Stamattina il<strong> presidente regionale di Legambiente, Francesco Falcone,<\/strong> \u00e8 intervenuto sull&#8217;argomento ai microfoni di RLB Radioattiva.<\/p>\n<h4><span style=\"color: #ff0000;\"><strong>ASCOLTA L&#8217;AUDIO INTERVISTA<\/strong><\/span><\/h4>\n<p>[audio_mp3 url=&#8221;http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/08\/Legambiente-Presidente-Francesco-Falcone.mp3&#8243;]<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Calabria ha bisogno di verit\u00e0 sui disastri naturali che la colpiscono, perch\u00e8 aldil\u00e0 dell&#8217;evento atmosferico straordinario, esiste una precisa responsabilit\u00e0 sull&#8217;incuria e la gestione del suolo e del territorio.<\/p>\n","protected":false},"author":22,"featured_media":46873,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-46892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/46892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=46892"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/46892\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/46873"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=46892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=46892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=46892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}