{"id":47341,"date":"2015-09-14T11:03:25","date_gmt":"2015-09-14T09:03:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/viabilita-chiuso-tratto-della-statale-18-nei-pressi-di-amantea\/"},"modified":"2023-01-17T12:39:00","modified_gmt":"2023-01-17T11:39:00","slug":"51258-viabilita-chiuso-tratto-della-statale-18-nei-pressi-di-amantea","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/51258-viabilita-chiuso-tratto-della-statale-18-nei-pressi-di-amantea\/","title":{"rendered":"Viabilit\u00e0, chiuso tratto della statale 18 nei pressi di Amantea"},"content":{"rendered":"<h4>Traffico interdetto ai veicoli non autorizzati per consentire lavori sulle linee telefoniche.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">AMANTEA (CS) &#8211;\u00a0Anas comunica che, per permettere ad una societ\u00e0 di telefonia di effettuare lavori per la sostituzione di alcuni cavi, esclusivamente tra le 7.00 e le 17.00 di domani, Marted\u00ec 15 Settembre, sulla strada statale 18 &#8220;Tirrena Inferiore&#8221; sar\u00e0 chiuso il tratto compreso tra il chilometro 345,800 e il chilometro 348,700, nel territorio comunale di Amantea, in provincia di Cosenza.\u00a0 I veicoli in direzione sud (Cosenza &#8211; Reggio Calabria) verranno deviati lungo la ex SS 18 (vecchia sede, strada comunale Localit\u00e0 Tonnara) e viceversa per la direzione nord (Salerno).\u00a0In corrispondenza del cantiere viger\u00e0 il limite di velocit\u00e0 di 30 chilometri orari ed il divieto di sorpasso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Traffico interdetto ai veicoli non autorizzati per consentire lavori sulle linee telefoniche.<\/p>\n","protected":false},"author":22,"featured_media":47342,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-47341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/47341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=47341"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/47341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/47342"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=47341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=47341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=47341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}