{"id":47359,"date":"2015-09-14T14:13:06","date_gmt":"2015-09-14T12:13:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-moscato-passito-viola-ancora-una-volta-vino-slow-nella-guida-gambero-rosso\/"},"modified":"2023-01-17T12:39:01","modified_gmt":"2023-01-17T11:39:01","slug":"51307-il-moscato-passito-viola-ancora-una-volta-vino-slow-nella-guida-gambero-rosso","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/51307-il-moscato-passito-viola-ancora-una-volta-vino-slow-nella-guida-gambero-rosso\/","title":{"rendered":"Il Moscato Passito &#8221;Viola&#8221; ancora una volta vino Slow nella guida Gambero Rosso"},"content":{"rendered":"<h4><strong>Ancora premi, soddisfazioni e riconoscimenti.<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SARACENA (CS) &#8211; Il celeberrimo Moscato Passito, tanto amato dai Papi nei secoli passati, \u00e8 stato confermato, col massimo punteggio, vino Slow nella guida Slow Wine 2016. E Saracena, continua ad affermarsi territorio di eccellenza e qualit\u00e0 nell&#8217;agroalimentare, in Italia e nel mondo.\u00a0\u00c8 l\u2019ottava volta consecutiva, inoltre, che il pregiato vino dolce prodotto dalle cantine Viola <strong>viene segnalato con i Tre Bicchieri nella guida ai Vini d\u2019Italia di Gambero Rosso<\/strong> che seleziona e premia, ogni anno, i migliori prodotti recensiti dai degustatori, inviati speciali, nell\u2019Italia delle eccellenze vitivinicole.\u00a0E nell\u2019anno di Expo Milano 2015, dedicato al tema \u201cNutrire il Pianeta, Energia per la Vita\u201d, gli apprezzamenti ed i riconoscimenti per questo prodotto d\u2019eccellenza ed in generale il terroir di Saracena e del Pollino pesano ancora di pi\u00f9.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c8 accaduto cos\u00ec, ad esempio, quando <strong>lo chef internazionale Francesco Mazzei ha scelto proprio il Moscato Passito \u2013 Presidio Slow Food a rappresentare l\u2019Italia, per realizzare un piatto speciale<\/strong> all\u2019interno del format londinese televisivo The Wine Show. Oppure quando Silvio Greco lo ha portato al ristorante Eataly all&#8217;Expo, per il giorno di Ferragosto, raccogliendo successi e apprezzamenti. Tra gli altri, anche quelli dello chef stellato Lucio Pompili e del maestro Francesco Rubino.\u00a0Nello stesso ristorante Eataly, dedicato alle cucine regionali in cui la Calabria, per tutto il mese di settembre, rester\u00e0 rappresentata da un altro testimone della vitalit\u00e0 enogastronomica e del ritorno alla terra, il giovane chef saracenaro Gennaro Di Pace, anima dell\u2019Osteria Porta del vaglio nel cuore del caratteristico centro storico di tradizioni arabe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ancora premi, soddisfazioni e riconoscimenti.<\/p>\n","protected":false},"author":22,"featured_media":47360,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,63,34],"tags":[],"class_list":["post-47359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-gusto","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/47359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=47359"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/47359\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/47360"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=47359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=47359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=47359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}