{"id":4736,"date":"2012-10-02T07:10:33","date_gmt":"2012-10-02T05:10:33","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=4736"},"modified":"2023-01-17T13:38:01","modified_gmt":"2023-01-17T12:38:01","slug":"1639-esplosione-in-una-centrale-elettrica-nessun-ferito","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/1639-esplosione-in-una-centrale-elettrica-nessun-ferito\/","title":{"rendered":"Esplosione in una centrale elettrica, nessun ferito"},"content":{"rendered":"<p style=\"text-align: justify;\">SCANDALE(KR) &#8211; Esplosione e relativo incendio a Scandale, in provincia di Crotone.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Vittima: una centrale elettrica Terna in Localita&#8217; Santa Domenica nel Comune di Scandale, nel&nbsp;Crotonese. Ad esplodere e&#8217; stato un isolante ad alta tensione 380.000 Volt probabilmente a causa di un sovraccarico e il mancato intervento dei dispositivi di sicurezza. Il tempestivo intervento dei Vigili del Fuoco intervenuti intorno alle 3,41, coordinati dal Capo Squadra Federico Giuseppe ha imedito che l&#8217;incendio non si propagasse agli altri isolatori vicini . I pezzi di porcellana facente parte dell&#8217; isolatore esplosi sono stati trovati a circa 50 metri di distanza. Nella stessa notte i Vigili sono stati impegnati a&nbsp;Crotone&nbsp;per l&#8217; incendio di un&#8217; autovettura in Localita&#8217; Farina e per spegnere altri cinque incendi di sterpaglie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SCANDALE(KR) &#8211; Esplosione e relativo incendio a Scandale, in provincia di Crotone.<\/p>\n","protected":false},"author":22,"featured_media":4737,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18,5],"tags":[],"class_list":["post-4736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=4736"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/4737"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=4736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=4736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=4736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}