{"id":4740,"date":"2012-10-02T07:34:28","date_gmt":"2012-10-02T05:34:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=4740"},"modified":"2023-01-17T13:38:01","modified_gmt":"2023-01-17T12:38:01","slug":"1641-collisione-fra-traghetti-a-hong-kong-36-morti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/1641-collisione-fra-traghetti-a-hong-kong-36-morti\/","title":{"rendered":"Collisione fra traghetti a Hong Kong: 36 morti"},"content":{"rendered":"<div style=\"text-align: justify;\">Almeno 36 persone sono morte e decine sono rimaste ferite gravemente su un traghetto che,<\/div>\n<p>  <!--more-->  <\/p>\n<div style=\"text-align: justify;\">dopo la collisione con un altro si \u00e8 capovolto ed \u00e8 affondato vicino all&#8217;isola di Lamma, a sud di Hong Kong. I soccorsi a bordo del mezzo, sul quale viaggiavano pi\u00f9 di 120 passeggeri, sono resi difficili dalla scarsa visibilit\u00e0. Il ferry della Hong Kong Electric Company navigava in notturna per consentire alle persone di vedere i fuochi d&#8217;artificio dal mare.<\/div>\n<div>La tragedia \u00e8 avvenuta alle 8.25 locali, mentre il Porto di Vittoria era illuminato dai fuochi d&#8217;artificio per le celebrazioni della festa nazionale cinese del 1 ottobre.<br \/><br type=\"_moz\" \/>Stando a una prima ricostruzione degli eventi il Lamma IV, un traghetto della Hongkong Electric, \u00e8 stato urtato da un altro traghetto passeggeri che arrivava da Central, sull&#8217;isola di Hong Kong, a tutta velocit\u00e0. <\/p>\n<p style=\"text-align: justify;\">In acqua sono finite 124 persone. Si tratta di uno dei pi\u00f9 gravi incidenti marittimi nelle acque di Hong Kong in tempi recenti. Il territorio, composto da due isole principali, la penisola di Kowloon e decine di altre isole, ha uno dei porti pi\u00f9 trafficati al mondo, ma gli incidenti sono molto rari.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Almeno 36 persone sono morte e decine sono rimaste ferite gravemente su un traghetto che,<\/p>\n","protected":false},"author":22,"featured_media":4741,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,22,5],"tags":[],"class_list":["post-4740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dal-mondo","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=4740"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/4741"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=4740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=4740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=4740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}