{"id":4756,"date":"2012-10-02T09:10:34","date_gmt":"2012-10-02T07:10:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=4756"},"modified":"2023-01-17T13:38:05","modified_gmt":"2023-01-17T12:38:05","slug":"1649-napoli-fli-no-chiusura-carcere-modello-di-laureana","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/1649-napoli-fli-no-chiusura-carcere-modello-di-laureana\/","title":{"rendered":"Napoli (Fli), no chiusura carcere modello di Laureana"},"content":{"rendered":"<p>(ASCA) &#8211; Catanzaro, 2 ott &#8211; &#8221;Il sovraffollamento delle carceri italiane richiede con urgenza norme legislative che possano in qualche modo aiutare i detenuti affinche&#8217; vengano garantiti i diritti umani; la mancanza di finanziamenti adeguati, le lentezze burocratiche, ma anche, a volte, difficolta&#8217; nel monitorare le<\/p>\n<p>  <!--more-->  <\/p>\n<p>situazioni esistenti, hanno per troppo tempo rallentato il c.d. &#8221;piano carceri&#8221;, il che&#8217; dovrebbe custodire, al momento, le strutture esistenti in modo da garantire la buona distribuzione dei detenuti&#8221;. Lo scrive Angela Napoli, deputata di Fli, in una interrogazione rivolta al Ministro della Giustizia.<\/p>\n<p>&#8221;L&#8217;Istituto penitenziario &#8221;Luigi Daga&#8221; di Laureana di Borrello (R.C.) era una struttura &#8221;modello&#8221; e sperimentale in grado di contenere 68 detenuti, per lo piu&#8217; giovani, tra i 18 e i 34 anni di eta&#8217;, ai quali poteva venire garantito un percorso di detenzione associato ad un&#8217;adeguata attivita&#8217; di laboratorio: tre serre, una falegnameria e un laboratorio di ceramica; nel corso dell&#8217;anno la falegnameria pur lavorando a singhiozzo a causa dei tagli di bilancio, e&#8217; riuscita, grazie al lavoro di 4 detenuti, a fornire tutto il mobilio per arredare il carcere di Crotone; due giorni fa i 29 detenuti (incomprensibile il numero di presenti a fronte dei 68 posti previsti) &#8211; afferma Napoli &#8211; sono stati improvvisamente trasferiti, contribuendo cosi&#8217; all&#8217;aumento del gia&#8217; presente sovraffollamento negli altri Istituti e il personale di Polizia Penitenziaria, tutto distaccato, rientrera&#8217; nelle sedi di provenienza, mentre quello appartenente al Comparto Ministeri, effettivamente assegnato all&#8217;Istituto, senza essere interpellato e senza consultazione delle organizzazioni sindacali, e&#8217; stato gia&#8217; dislocato presso tutti gli Istituti della Calabria&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(ASCA) &#8211; Catanzaro, 2 ott &#8211; &#8221;Il sovraffollamento delle carceri italiane richiede con urgenza norme legislative che possano in qualche modo aiutare i detenuti affinche&#8217; vengano garantiti i diritti umani; la mancanza di finanziamenti adeguati, le lentezze burocratiche, ma anche, a volte, difficolta&#8217; nel monitorare le<\/p>\n","protected":false},"author":22,"featured_media":4757,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17,5],"tags":[],"class_list":["post-4756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=4756"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4756\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/4757"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=4756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=4756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=4756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}