{"id":47577,"date":"2015-09-21T12:39:43","date_gmt":"2015-09-21T10:39:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/autovelox-sulla-statale-18-nuovo-presidio-nel-comune-di-amantea\/"},"modified":"2023-01-17T12:39:14","modified_gmt":"2023-01-17T11:39:14","slug":"52074-autovelox-sulla-statale-18-nuovo-presidio-nel-comune-di-amantea","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/52074-autovelox-sulla-statale-18-nuovo-presidio-nel-comune-di-amantea\/","title":{"rendered":"Autovelox sulla statale 18, nuovo presidio nel Comune di Amantea"},"content":{"rendered":"<h4>Da Mercoled\u00ec in localit\u00e0 Aquicella sar\u00e0 attiva la postazione dei vigili urbani con l\u2019autovelox.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">AMANTEA (CS) &#8211; Il comando di polizia municipale di Amantea ha ufficializzato il calendario degli orari in cui sul comprensorio amanteano sar\u00e0 attivo l\u2019autovelox. A partire dal prossimo 23 settembre, infatti, i vigili urbani presidieranno la Ss 18 all\u2019altezza di localit\u00e0 Aquicella, montando le apparecchiature idonee al rilevamento della velocit\u00e0 dei veicoli in transito. Una misura in qualche modo attesa ed anche auspicata, considerando <strong>le alte velocit\u00e0 che spesso si verificano in quel tratto, teatro in passato di incidenti e sinistri purtroppo gravi. &#8220;<\/strong>Avviando questa operazione \u2013 spiega il comandato della polizia municipale Emilio\u00a0Caruso \u2013 rispondiamo alle numerose istanze che sono giunte dai residenti della localit\u00e0 situata all\u2019ingresso del lato Nord di Amantea. Acquicella \u00e8 una contrada molto rilevante dal punto di vista demografico e non presenta, purtroppo, itinerari alternativi alla Ss 18. Chi ha esigenza di spostarsi verso il centro della citt\u00e0 non pu\u00f2 fare altro che utilizzare la Statale e in alcuni casi la visibilit\u00e0 per l\u2019immissione dei mezzi \u00e8 davvero ridotta.<\/p>\n<p>&nbsp;<br \/>\n&nbsp;<\/p>\n<p style=\"text-align: justify;\">La litorale tirrenica in quel tratto corre in rettilineo: una circostanza che di certo non incita gli automobilisti a rallentare, nonostante sia vigente il limite di velocit\u00e0 derivante dall\u2019attraversamento di un centro urbano. Per risolvere questa situazione abbiamo varato un programma che prevede la presenza dell\u2019autovelox a partire dal prossimo 23 settembre. <strong>Mercoled\u00ec la pattuglia della Municipale sar\u00e0 operativa dalle 14 alle 18; sabato dalle 10 alle 18 e il luned\u00ec successivo dalle 14 alle 18&#8243;<\/strong>.\u00a0Comunicando gli orari in cui l\u2019autovelox sar\u00e0 attivo il comando di Polizia Municipale ha ottemperato anche a quanto previsto dalla normativa vigente ed in particolare dalla circolare del Ministero dell\u2019interno numero 10307 del 14 agosto 2009 che regola il funzionamento di questo tipo di impianto. Gli aggiornamenti relative alle modifiche del calendario verranno tempestivamente comunicate, utilizzando anche gli spazi ufficiali online a disposizione dell\u2019ente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da Mercoled\u00ec in localit\u00e0 Aquicella sar\u00e0 attiva la postazione dei vigili urbani con l\u2019autovelox.<\/p>\n","protected":false},"author":22,"featured_media":47578,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-47577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/47577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=47577"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/47577\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/47578"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=47577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=47577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=47577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}