{"id":47579,"date":"2015-09-23T13:00:45","date_gmt":"2015-09-23T11:00:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/due-giorni-di-chiusura-per-lufficio-postale-di-via-veneto-a-cosenza\/"},"modified":"2023-01-17T12:39:14","modified_gmt":"2023-01-17T11:39:14","slug":"52081-due-giorni-di-chiusura-per-lufficio-postale-di-via-veneto-a-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/52081-due-giorni-di-chiusura-per-lufficio-postale-di-via-veneto-a-cosenza\/","title":{"rendered":"Due giorni di chiusura per l&#8217;Ufficio postale di Via Veneto, a Cosenza"},"content":{"rendered":"<h4><strong>L\u2019Ufficio postale di Cosenza, situato in via Veneto, rester\u00e0 chiuso al pubblico\u00a0nelle giornate del 25 e 26 settembre per consentire l&#8217;installazione del nuovo &#8216;gestore delle attese&#8217;.\u00a0<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; A comunicarlo \u00e8\u00a0il direttore di filiale, che consiglia all\u2019utenza\u00a0di rivolgersi agli uffici postali pi\u00f9 vicini, la succursale 4 di via\u00a0XXIV maggio, aperta dal luned\u00ec al venerd\u00ec dalle 8.20 alle 13.35 e\u00a0nella giornata di sabato dalle 8,20 alle 12,35; oppure alla succursale\u00a07 di corso d\u2019Italia, aperta dal luned\u00ec al venerd\u00ec dalle 8,20 alle 19.05\u00a0e nella giornata di sabato dalle 8.20 alle 12.35.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Ufficio postale di Cosenza, situato in via Veneto, rester\u00e0 chiuso al pubblico\u00a0nelle giornate del 25 e 26 settembre per consentire l&#8217;installazione del nuovo &#8216;gestore delle attese&#8217;.\u00a0<\/p>\n","protected":false},"author":22,"featured_media":47580,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-47579","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/47579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=47579"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/47579\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/47580"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=47579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=47579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=47579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}