{"id":47656,"date":"2015-09-23T13:25:27","date_gmt":"2015-09-23T11:25:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/mar-jonio-il-referendum-antitrivelle-venerdi-sara-discusso-in-consiglio-regionale\/"},"modified":"2023-01-17T12:39:18","modified_gmt":"2023-01-17T11:39:18","slug":"52395-mar-jonio-il-referendum-antitrivelle-venerdi-sara-discusso-in-consiglio-regionale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/52395-mar-jonio-il-referendum-antitrivelle-venerdi-sara-discusso-in-consiglio-regionale\/","title":{"rendered":"Mar Jonio, il referendum antitrivelle venerd\u00ec sar\u00e0 discusso in consiglio regionale (AUDIO INTERVISTA)"},"content":{"rendered":"<h4><strong>Sale il numero delle regioni del Sud che stanno approvando le deliberazioni sui quesiti referendari \u201cNo Triv\u201d.<\/strong><\/h4>\n<p><!--more--><\/p>\n<p>COSENZA &#8211; Venerd\u00ec 25 settembre anche la Calabria \u00e8 chiamata a pronunciarsi sul referendum che avr\u00e0 l\u2019obiettivo di fermare la caccia al petrolio davanti alle coste italiane e a ridare diritti ai territori senza scavalcarli. La parola passa ora alla Corte di Cassazione. Il movimento antitrivelle delle Regioni prosegue a passo spedito la sua attivit\u00e0 ed \u00e8 di pochi giorni fa, il s\u00ec ai referendum antitrivelle dei Consigli regionali di Puglia, Marche, Molise e Sardegna. \u00c8 stata rinviata invece la decisione del Consiglio regionale dell\u2019Umbria, perch\u00e9 in Commissione i rappresentanti del Pd hanno chiesto di approfondire la questione. A breve arriver\u00e0 anche la decisione della Sicilia, dell&#8217;Abruzzo e della Campania, e venerd\u00ec toccher\u00e0 a Veneto e Calabria; per finire il 29 settembre prossimo alla Liguria. \u00c8 stata la Basilicata la prima Regione a votare le delibere per attivare la richiesta di referendum abrogativi di alcune parti dell\u2019articolo 38 del decreto legge Sblocca Italia (convertito con modificazioni nella legge 164 del 2014), nonch\u00e9 delle norme ad esso correlate contenute nell\u2019articolo 57 del decreto legge numero 5 del 2012 (il cosiddetto decreto \u201cSemplificazione e sviluppo\u201d varato dal governo Monti) e nell\u2019articolo 1 della legge 239 del 2014. C\u2019\u00e8, poi, il dato politico: tutte le Regioni sulle barricate \u201cno triv\u201d sono governate dal Pd, il partito del premier Matteo Renzi. Secondo i dettami della Costituzione italiana, i quesiti da sottoporre alla consultazione referendaria devono essere depositati all\u2019Ufficio centrale presso la Corte di Cassazione da almeno cinque Regioni. La consegna dovr\u00e0 avvenire entro il 30 settembre. Le Regioni a favore del referendum contro le trivellazioni in mare concesse dalla normativa \u201csblocca Italia\u201d sono undici, con la Basilicata capofila. La richiesta di cancellazione riguarda anche le norme che prevedono fino all\u2019esproprio di terreni sotto i quali si ipotizza la presenza di petrolio.<\/p>\n<p>Il rappresentante del <strong>comitato No Triv di Rossano, Flavio Stasi,<\/strong> questa mattina \u00e8 stato intervistato ai microfoni di <strong>Rlb Radioattiva<\/strong>, e oltre ad esprimere soddisfazione per la grande adesione da parte delle Regioni, ha sottolineato ancora una volta i motivi che spingono i territori interessati a fermare la possibilit\u00e0 di trivellare il mare.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>ASCOLTA L&#8217;INTERVISTA<\/strong><\/span><\/p>\n<p>[audio_mp3 url=&#8221;http:\/\/www.quicosenza.it\/news\/wp-content\/uploads\/2015\/09\/Flavio-Stasi-No-Triv.mp3&#8243;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sale il numero delle regioni del Sud che stanno approvando le deliberazioni sui quesiti referendari \u201cNo Triv\u201d.<\/p>\n","protected":false},"author":19,"featured_media":47657,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-47656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/47656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=47656"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/47656\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/47657"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=47656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=47656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=47656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}