{"id":47695,"date":"2015-09-24T10:55:16","date_gmt":"2015-09-24T08:55:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rapina-al-corriere-bartolini-ritrovata-unauto-simile-a-quella-usata-dai-rapinatori\/"},"modified":"2023-01-17T12:39:20","modified_gmt":"2023-01-17T11:39:20","slug":"52503-rapina-al-corriere-bartolini-ritrovata-unauto-simile-a-quella-usata-dai-rapinatori","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/52503-rapina-al-corriere-bartolini-ritrovata-unauto-simile-a-quella-usata-dai-rapinatori\/","title":{"rendered":"Rapina al corriere Bartolini, ritrovata un&#8217;auto simile a quella usata dai rapinatori"},"content":{"rendered":"<h4>I quattro rapinatori non sono ancora stati rintracciati dagli inquirenti.<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">RENDE &#8211; Inquirenti al lavoro per stabilire l&#8217;identit\u00e0 dei malviventi appostati nei pressi del deposito del corriere espresso Bartolini in contrada Lecco. I quattro, marted\u00ec sera intorno alle 19.30 dopo aver atteso che un camion rientrasse si sono accodati al mezzo e hanno fatto irruzione nei magazzini. A volto coperto e armati di revolver, hanno aggredito l&#8217;autista facendosi consegnare il portafogli all&#8217;interno del quale il dipendente conservava il denaro della ditta: 1.200 euro in contanti e 2mila euro di assegni. Dopo aver disarmato e pestato il vigilante della struttura con calci e un forte colpo al capo sono corsi verso la cassa continua prelevando l&#8217;incasso della giornata pari ad 8mila 500 euro. <strong>Poi hanno tentato un gesto azzardato, scardinare la cassaforte centrale.<\/strong> Un tentativo che ha fatto scattare le sirene e allertato automaticamente le forze dell&#8217;ordine. All&#8217;arrivo dei carabinieri per\u00f2 i rapinatori sono riusciti a fuggire ad alta velocit\u00e0 dalla zona industriale e confondersi nel traffico facendo perdere le proprie tracce.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Le telecamere di videosorveglianza hanno permesso di stabilire che l&#8217;assalto a mano armata al deposito \u00e8 avvenuto a bordo di una Fiat Uno Bianca, lo stesso modello di auto ritrovato abbandonato in contrada Coda di Volpe poche ore dopo. Il veicolo pare fosse\u00a0stato rubato ad Amantea nei giorni scorsi, ma al suo interno non sarebbe stato rinvenuto nessun oggetto riconducibile alla rapina. Due settimane fa, sempre con una Fiat Uno rubata, tre malviventi armati ed a volto coperto avevano sbarrato la strada ad un furgone facendosi consegnare dall&#8217;autista 20mila euro. Anche in questo caso i rapinatori scomparvero nel nulla non lasciando alcun indizio che possa ricondurre alla loro identit\u00e0. <strong>A Tortora invece in Aprile un assalto plateale con un finto posto di blocco e dei finti poliziotti\u00a0aveva portato nelle mani del commando 700mila euro.<\/strong> Episodi che farebbero pensare al ritorno della banda degli assalti ai furgoni dopo anni di inattivit\u00e0. Come ai tempi di Franchino &#8216;i Mafarda&#8217; con &#8216;professionisti&#8217;\u00a0attenti ai dettagli, addestrati per rapinare portavalori, che dal 1997 al 2006 hanno terrorizzato autisti e corrieri del cosentino.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: right;\">Immagine di repertorio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I quattro rapinatori non sono ancora stati rintracciati dagli inquirenti.<\/p>\n","protected":false},"author":18,"featured_media":47696,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,44],"tags":[],"class_list":["post-47695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/47695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=47695"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/47695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/47696"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=47695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=47695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=47695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}