{"id":4796,"date":"2012-10-02T13:09:04","date_gmt":"2012-10-02T11:09:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=4796"},"modified":"2023-01-17T13:38:07","modified_gmt":"2023-01-17T12:38:07","slug":"1672-vibo-valentia-atto-intimidatorio-al-vicesindaco-incendiata-la-sua-auto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/1672-vibo-valentia-atto-intimidatorio-al-vicesindaco-incendiata-la-sua-auto\/","title":{"rendered":"Vibo Valentia, atto intimidatorio al vicesindaco: incendiata la sua auto"},"content":{"rendered":"<p style=\"text-align: justify;\">(Adnkronos) &#8211; Un atto intimidatorio ha colpito nella notte il vicesindaco di Vibo Valentia Salvatore Bulzomi&#8217;,<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">che in giunta ha anche la delega ai servizi sociali. Ignoti hanno incendiato la Nissan Micra di sua proprieta&#8217; che era parcheggiata sotto casa. I capigruppo di maggioranza del gruppo consiliare di Pdl Mario Mazzeo, con il vice capogruppo Raffaele Manduca, Giulio Capria (della lista Per Vibo con D&#8217;Agostino) con il vice Antonio Schiavello, Gregorio La Gamba (Insieme per Vibo) e Pino Pugliese (Udc), hanno imemdiatamente espresso vicinanza.<\/p>\n<p style=\"text-align: justify;\">&#8221;A nome di tutti i consiglieri -hanno dichiarato in una nota- invitiamo l&#8217;assessore ad andare avanti, nella ferma convinzione che lo stesso continuera&#8217; ad apportare alla citta&#8217; un reale beneficio, con correttezza e rispetto delle regole morali e civili, che sono, non dimentichiamolo, alla base del viver civile&#8221;.Solidarieta&#8217; anche dall&#8217;assessore regionale alle attivita&#8217; produttive Antonio Caridi. &#8221;Al vicesindaco di Vibo e a tutti gli amministratori vittime di atti delinquenziali &#8211; ha affermato &#8211; confermo il pieno sostegno, personale e istituzionale, nella convinzione che il percorso di rinnovamento avviato a tutti i livelli sapra&#8217; portare a compimento il progetto di sviluppo economico e di crescita sociale e culturale per la Calabria ed i calabresi tutti&#8221;. Nel contempo Caridi ha espresso &#8221;ferma condanna verso ogni forma di violenza nei confronti di chi presta il proprio impegno quotidiano nelle istituzioni e nella societa&#8217; civile, ad ogni livello&#8221;.<\/p>\n<p><span style=\"color: #454545; font-family: Arial, Verdana, Tahoma; font-size: 14px; line-height: normal; background-color: #ffffff;\">&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Adnkronos) &#8211; Un atto intimidatorio ha colpito nella notte il vicesindaco di Vibo Valentia Salvatore Bulzomi&#8217;,<\/p>\n","protected":false},"author":22,"featured_media":4797,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18,5],"tags":[],"class_list":["post-4796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=4796"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/4796\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/4797"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=4796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=4796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=4796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}